{"id":10879,"date":"2015-10-30T19:15:24","date_gmt":"2015-10-30T18:15:24","guid":{"rendered":"http:\/\/www.ades-grenoble.org\/wordpress\/?p=10879"},"modified":"2015-10-30T19:17:13","modified_gmt":"2015-10-30T18:17:13","slug":"des-nanotubes-de-carbone-retrouves-dans-des-poumons-humains-a-paris","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2015\/10\/30\/des-nanotubes-de-carbone-retrouves-dans-des-poumons-humains-a-paris\/","title":{"rendered":"Des nanotubes de carbone retrouv\u00e9s dans des poumons humains \u00e0 Paris"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10500 alignleft\" src=\"http:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2015\/07\/Journal-environnement.jpg\" alt=\"Journal-environnement\" width=\"481\" height=\"53\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2015\/07\/Journal-environnement.jpg 481w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2015\/07\/Journal-environnement-150x17.jpg 150w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2015\/07\/Journal-environnement-300x33.jpg 300w\" sizes=\"auto, (max-width: 481px) 100vw, 481px\" \/>Le journal de l\u2019environnement (JDLE) a publi\u00e9 le 23 octobre un article qui informe sur une \u00e9tude qui montre que dans les poumons des enfants parisiens on trouve des nanotubes de carbone issus de la pollution atmosph\u00e9rique. <em>\u00ab\u00a0 Pour la premi\u00e8re fois, des nanotubes de carbone, issus de la pollution atmosph\u00e9rique, ont \u00e9t\u00e9 retrouv\u00e9s dans des poumons humains, lors d\u2019une <a href=\"http:\/\/www.sciencedirect.com\/science\/article\/pii\/S2352396415301754\">\u00e9tude franco-am\u00e9ricaine<\/a> publi\u00e9e dans la revue eBioMedicine.\u00a0\u00bb<\/em><!--more--><\/p>\n<p style=\"text-align: justify;\"><em>\u00ab\u00a0Une premi\u00e8re au monde, enfin presque : avant cela, ces nanotubes de carbone issus de la combustion (\u00e0 ne pas confondre avec ceux produits de mani\u00e8re synth\u00e9tique pour des applications industrielles) avaient \u00e9t\u00e9 retrouv\u00e9s dans les exsudats de survivants du World Trade Center, donc suite \u00e0 une exposition massive et accidentelle.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Men\u00e9e par Fathi Moussa, professeur de chimie \u00e0 l\u2019universit\u00e9 Paris-Sud et pharmacien biologiste \u00e0 l\u2019h\u00f4pital Trousseau (Paris), et ses coll\u00e8gues, cette \u00e9tude est la premi\u00e8re \u00e0 porter sur une exposition chronique \u00e0 la pollution urbaine. Pour cela, les chercheurs ont \u00e9tudi\u00e9 69 lavages broncho-alv\u00e9olaires de jeunes asthmatiques, \u00e2g\u00e9s de 2 mois \u00e0 17 ans, chez qui ces \u00e9chantillons sont pr\u00e9lev\u00e9s en routine dans les services de pneumo-allergologie.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>A l\u2019aide de diff\u00e9rentes m\u00e9thodes d\u2019analyse (microscopie \u00e9lectronique \u00e0 transmission, analyse dispersive en \u00e9nergie par rayons X), les chercheurs ont observ\u00e9, y compris \u00e0 l\u2019int\u00e9rieur de cellules pulmonaires, des nanotubes de carbone d\u2019un diam\u00e8tre compris entre 10 et 60 nanom\u00e8tres, et d\u2019une longueur de plusieurs centaines de nanom\u00e8tres. Les m\u00eames que ceux qu\u2019ils ont retrouv\u00e9s sur des pots d\u2019\u00e9chappement et dans de la poussi\u00e8re recueillie sur des fen\u00eatres.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong><em>Des m\u00e9canismes \u00e0 \u00e9lucider<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Quel impact sanitaire de ces nanotubes qui s\u2019accumulent dans nos poumons ? Certes, les effets des particules fines, en particulier les PM2,5 dont font partie ces nanotubes, ne font plus gu\u00e8re de doute : selon l\u2019Organisation mondiale de la sant\u00e9 (OMS), la pollution de l\u2019air a tu\u00e9 7 millions de personnes en 2012. Mais les m\u00e9canismes \u00e0 l\u2019\u0153uvre demeurent encore peu connus, tant la pollution atmosph\u00e9rique contient une grande vari\u00e9t\u00e9 de composants.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Men\u00e9s chez l\u2019animal, \u00ab des travaux ont d\u00e9j\u00e0 montr\u00e9 que lorsqu\u2019ils sont longs ou qu\u2019ils forment des agr\u00e9gats, les nanotubes de carbone engendrent des granulomes inflammatoires \u00bb \u00e0 l\u2019int\u00e9rieur des poumons, pouvant aller jusqu\u2019au cancer, explique Fathi Moussa au JDLE. Pourtant, la taille des nanotubes d\u00e9couverts par les chercheurs semble inf\u00e9rieure \u00e0 celle requise \u00e0 cet effet, proche de l\u2019amiante.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00ab Ce qui est certain, c\u2019est que ces particules [du fait de leur petite taille] ont une tr\u00e8s grande surface sp\u00e9cifique, qui leur permet d\u2019absorber un tr\u00e8s grand nombre de composants \u00bb<\/em><em> qu\u2019ils c\u00f4toient dans l\u2019air (gaz, m\u00e9taux, autres particules), dont la toxicit\u00e9 serait renforc\u00e9e par l\u2019effet de concentration. En cela, ces nanotubes pourraient agir\u00a0comme \u00ab nanovecteurs \u00bb, avance Fathi Moussa, qui pointe les nombreuses inconnues quant \u00e0 leur devenir.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">Pour lire l&rsquo;article complet cliquez <a href=\"http:\/\/www.journaldelenvironnement.net\/article\/des-nanotubes-de-carbone-retrouves-dans-des-poumons-humains,63261?xtor=EPR-9\" target=\"_blank\">ici<\/a>.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Le journal de l\u2019environnement (JDLE) a publi\u00e9 le 23 octobre un article qui informe sur une \u00e9tude qui montre que dans les poumons des enfants parisiens on trouve des nanotubes de carbone issus de la pollution atmosph\u00e9rique. \u00ab\u00a0 Pour la premi\u00e8re fois, des nanotubes de carbone, issus de la pollution atmosph\u00e9rique, ont \u00e9t\u00e9 retrouv\u00e9s dans [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11,135],"tags":[122,99],"class_list":["post-10879","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","category-pollution","tag-pollution-atmospherique","tag-sante"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/10879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=10879"}],"version-history":[{"count":3,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/10879\/revisions"}],"predecessor-version":[{"id":10882,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/10879\/revisions\/10882"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=10879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=10879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=10879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}