{"id":11505,"date":"2016-04-08T14:21:59","date_gmt":"2016-04-08T13:21:59","guid":{"rendered":"http:\/\/www.ades-grenoble.org\/wordpress\/?p=11505"},"modified":"2016-04-09T16:39:49","modified_gmt":"2016-04-09T15:39:49","slug":"vision-grenobloise-de-panama-papers","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2016\/04\/08\/vision-grenobloise-de-panama-papers\/","title":{"rendered":"Vision grenobloise de \u00ab Panama papers \u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11506 alignleft\" src=\"http:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2016\/04\/Sainte-Cecile-300x198.jpg\" alt=\"Sainte-Cecile\" width=\"300\" height=\"198\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2016\/04\/Sainte-Cecile-300x198.jpg 300w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2016\/04\/Sainte-Cecile-150x99.jpg 150w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2016\/04\/Sainte-Cecile.jpg 350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Le 7 avril, l<a href=\"http:\/\/www.lemonde.fr\/panama-papers\/article\/2016\/04\/06\/panama-papers-ces-riches-francais-qui-dissimulent-leurs-avoirs_4896660_4890278.html#huit-anchor-actionsauporteur\" target=\"_blank\">\u2019enqu\u00eate du Monde sur les paradis fiscaux<\/a> rapporte comment J. Gl\u00e9nat, \u00e9diteur grenoblois de bandes dessin\u00e9es a utilis\u00e9 les services du cabinet d\u2019avocat Mossack Fonseca au centre du scandale \u00ab\u00a0Panama papers\u00a0\u00bb (voir plus loin).<\/p>\n<p style=\"text-align: justify;\">Dans <a href=\"http:\/\/www.huffingtonpost.fr\/denis-dupre\/comment-97-des-deputes-ont-fait-capoter-la-loi-pour-lutter-contre-levasion-fiscale_b_8911440.html\" target=\"_blank\">un article de janvier 2016<\/a>, D. Dupr\u00e9 enseignant-chercheur en finance \u00e0 l&rsquo;universit\u00e9 de Grenoble explique comment 97% des d\u00e9put\u00e9s ont, en d\u00e9cembre 2015, emp\u00each\u00e9 le vote d\u2019un amendement qui visait \u00e0 lutter contre l\u2019\u00e9vasion fiscale. Alors que le gouvernement impose une cure d&rsquo;aust\u00e9rit\u00e9 sans pr\u00e9c\u00e9dent, 40 \u00e0 60 milliards d&rsquo;euros \u00e9chappent \u00e0 l&rsquo;imp\u00f4t par an (la commission europ\u00e9enne estime que ce sont 1000 milliards \u00e0 l&rsquo;\u00e9chelle de l&rsquo;Europe)\u00a0; l&rsquo;absence de\u00a0531 d\u00e9put\u00e9s a permis de repousser un amendement obligeant les multinationales \u00e0 la transparence.\u00a0Malheureusement les d\u00e9put\u00e9s de l&rsquo;Is\u00e8re font partie des d\u00e9serteurs.\u00a0Plut\u00f4t que de d\u00e9fendre les Grenoblois et les Is\u00e9rois contre l&rsquo;exil fiscal, ils pr\u00e9f\u00e8rent voter l&rsquo;aust\u00e9rit\u00e9 impos\u00e9e !<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Extrait de l\u2019<a href=\"http:\/\/www.lemonde.fr\/panama-papers\/article\/2016\/04\/06\/panama-papers-ces-riches-francais-qui-dissimulent-leurs-avoirs_4896660_4890278.html#huit-anchor-actionsauporteur\" target=\"_blank\">article du Monde du 7 avril 2018<\/a>\u00a0: \u00e0 noter que J. Gl\u00e9nat d\u00e9ment avoir \u00e9t\u00e9 propri\u00e9taire de Getway S.A.<\/p>\n<p style=\"text-align: justify;\"><em>\u00ab\u00a0En 2009, Jacques Gl\u00e9nat se porte acqu\u00e9reur de Getway S.A., une soci\u00e9t\u00e9 domicili\u00e9e aux Seychelles. Celle-ci est propri\u00e9taire d\u2019un compte bancaire et est utilis\u00e9e notamment pour acheter des \u0153uvres d\u2019art. Selon les documents consult\u00e9s par Le Monde, pendant les quelques ann\u00e9es o\u00f9 il a poss\u00e9d\u00e9 la soci\u00e9t\u00e9, 4 millions d\u2019euros ont \u00e9t\u00e9 plac\u00e9s sur ses comptes. Cette soci\u00e9t\u00e9 a par ailleurs amass\u00e9 de nombreux tableaux \u2013 des Bruegel le jeune, un Corot, des Cranach, des Fantin-Latour, des Felix Ziem, etc. \u2013 mais aussi des bronzes ou de l\u2019\u00e9b\u00e9nisterie ancienne. Certaines de ces \u0153uvres ont \u00e9t\u00e9 achet\u00e9es aux ench\u00e8res.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Tout semblait destiner Getway S.A. \u00e0 rester une structure opaque sans que le nom de M. Gl\u00e9nat n\u2019apparaisse. Mais c\u2019\u00e9tait sans compter sur la r\u00e9forme de la l\u00e9gislation des \u00eeles Vierges britanniques, entr\u00e9e en vigueur le 1er janvier 2014. Il faudra d\u00e9sormais fournir un rapport financier annuel de la soci\u00e9t\u00e9 mais, surtout, troquer les discr\u00e8tes actions au porteur (anonymes) des soci\u00e9t\u00e9s pour des actions nominatives : c\u2019est une couche d\u2019opacit\u00e9 qui s\u2019efface, puisque le nom des actionnaires doit d\u00e9sormais \u00eatre renseign\u00e9. Mossack Fonseca, somm\u00e9 par les autorit\u00e9s de respecter ces nouvelles r\u00e8gles, demande avec insistance le nom de l\u2019actionnaire, mais le cabinet fiscaliste de Jacques Gl\u00e9nat, RSM Luxembourg, fait la sourde oreille pendant de longs mois.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Ce n\u2019est qu\u2019en mai 2014 qu\u2019une r\u00e9ponse est finalement donn\u00e9e : le b\u00e9n\u00e9ficiaire, plut\u00f4t que d\u2019appara\u00eetre sur les registres, pr\u00e9f\u00e8re fermer la soci\u00e9t\u00e9 seychelloise. En attendant la fermeture, qui peut prendre plusieurs mois, RSM demande \u00ab s\u2019il est possible de garder les actions au porteur, sachant que le client est pr\u00eat \u00e0 payer toute amende pour les conserver \u00bb. La requ\u00eate est accept\u00e9e, mais Mossack Fonseca demande n\u00e9anmoins \u00e0 conna\u00eetre le nom et l\u2019adresse du porteur des actions, en pr\u00e9cisant que l\u2019information restera dans ses fichiers internes. Un courriel auquel Le Monde a eu acc\u00e8s confirme le nom de l\u2019actionnaire ainsi que son adresse grenobloise. Les documents pr\u00e9parant la liquidation de la soci\u00e9t\u00e9 sont envoy\u00e9s dans la foul\u00e9e.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Au cours de l\u2019\u00e9t\u00e9 2014, la soci\u00e9t\u00e9 de Jacques Gl\u00e9nat distribue en dons manuels \u00e0 ses enfants les \u0153uvres d\u2019art, avant d\u2019\u00eatre dissoute en novembre. Contact\u00e9 par Le Monde, Jacques Gl\u00e9nat confirme bien que Getway S.A. a donn\u00e9 des \u0153uvres d\u2019art \u00e0 ses enfants, mais qu\u2019en revanche, \u00ab il n\u2019y a aucun lien direct entre cette soci\u00e9t\u00e9 et [lui]-m\u00eame. \u00bb. Quelques jours plus tard, il pr\u00e9cise que \u00ab s\u2019agissant d\u2019un compte de soci\u00e9t\u00e9, il n\u2019a pas a \u00eatre d\u00e9clar\u00e9 \u00e0 l\u2019administration fiscale si bien entendu, vous parlez du compte de la soci\u00e9t\u00e9 Getway. \u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Le 7 avril, l\u2019enqu\u00eate du Monde sur les paradis fiscaux rapporte comment J. Gl\u00e9nat, \u00e9diteur grenoblois de bandes dessin\u00e9es a utilis\u00e9 les services du cabinet d\u2019avocat Mossack Fonseca au centre du scandale \u00ab\u00a0Panama papers\u00a0\u00bb (voir plus loin). Dans un article de janvier 2016, D. Dupr\u00e9 enseignant-chercheur en finance \u00e0 l&rsquo;universit\u00e9 de Grenoble explique comment 97% [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[275,188],"class_list":["post-11505","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-evasion-fiscale","tag-transactions-financieres"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/11505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=11505"}],"version-history":[{"count":5,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/11505\/revisions"}],"predecessor-version":[{"id":11516,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/11505\/revisions\/11516"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=11505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=11505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=11505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}