{"id":12460,"date":"2017-01-13T10:16:21","date_gmt":"2017-01-13T09:16:21","guid":{"rendered":"http:\/\/www.ades-grenoble.org\/wordpress\/?p=12460"},"modified":"2017-01-13T10:50:50","modified_gmt":"2017-01-13T09:50:50","slug":"coeurs-de-villes-coeurs-de-metropole-les-dernieres-nouvelles","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2017\/01\/13\/coeurs-de-villes-coeurs-de-metropole-les-dernieres-nouvelles\/","title":{"rendered":"\u00ab C\u0153urs de villes, c\u0153urs de m\u00e9tropole \u00bb, les derni\u00e8res nouvelles"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12461 alignleft\" src=\"http:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/01\/CVCM.jpg\" alt=\"\" width=\"350\" height=\"260\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/01\/CVCM.jpg 350w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/01\/CVCM-150x111.jpg 150w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/01\/CVCM-300x223.jpg 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/>Le pr\u00e9sident de la M\u00e9tro, le<em> pr\u00e9sident du Syndicat mixte des transports en commun (SMTC), le vice-pr\u00e9sident de la M\u00e9tropole d\u00e9l\u00e9gu\u00e9 aux espaces publics et \u00e0 la voirie et le maire de Grenoble, ont pr\u00e9sent\u00e9 le bilan de la concertation sur le projet CVCM (C\u0153urs de villes, c\u0153urs de m\u00e9tropole) qui va augmenter la pi\u00e9tonnisation du centre de l\u2019agglom\u00e9ration afin de le revitaliser. La concertation a d\u00e9montr\u00e9 l\u2019adh\u00e9sion globale de la population aux grands objectifs du projet, m\u00eame si la pol\u00e9mique se poursuit sur la suppression des voitures sur l\u2019axe Agutte-Sembat, Rey.<\/em><\/p>\n<p style=\"text-align: justify;\">Les responsables m\u00e9tropolitains et communaux ont annonc\u00e9 que le Conseil de la m\u00e9tropole du 3 f\u00e9vrier prendra des d\u00e9cisions importantes qui seront ensuite prises en compte par le conseil municipal de Grenoble le 6 f\u00e9vrier.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Le Conseil de M\u00e9tro se prononcera sur\u00a0:<\/p>\n<ul style=\"text-align: justify;\">\n<li><em>La mise en \u0153uvre \u00e0 partir du printemps 2017 de l\u2019extension des zones pi\u00e9tonnes<\/em><\/li>\n<li><em>L\u2019\u00e9tude des \u00e9volutions possibles du fonctionnement des zones pi\u00e9tonnes<\/em><\/li>\n<li><em>Le lancement des \u00e9tudes\u00a0sur l\u2019am\u00e9nagement des boulevards Lyautey, Agutte-Sembat et Rey<\/em><\/li>\n<li><em>La mise en place d\u00e8s le printemps 2017 d\u2019un premier plan de circulation adapt\u00e9 (en raison de travaux concomitants men\u00e9s par la Compagnie de chauffage et d\u2019autres gestionnaires de r\u00e9seaux)<\/em><\/li>\n<li><em>Une meilleure accessibilit\u00e9 et lisibilit\u00e9 des parcs de stationnements publics du centre-ville<\/em><\/li>\n<li><em>Le lancement des \u00e9tudes pour l\u2019am\u00e9nagement du carrefour Gambetta-Berriat-Lafontaine-B\u00e9ranger<\/em><\/li>\n<li><em>Le lancement des \u00e9tudes sur le possible r\u00e9am\u00e9nagement de la place Championnet<\/em><\/li>\n<li><em>Le lancement des \u00e9tudes pour la r\u00e9alisation rapide de nombreux stationnements v\u00e9los<\/em><\/li>\n<li><em>Le d\u00e9veloppement des initiatives et r\u00e9alisations artistiques sur l\u2019espace public<\/em><\/li>\n<li><em>La mise en place d\u2019exp\u00e9rimentations et de tests d\u2019usages sur les diff\u00e9rents secteurs du projet<\/em><\/li>\n<li><em>La mise en place d\u2019un observatoire avec suivi r\u00e9gulier du projet.<\/em><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><em>Une nouvelle phase de dialogue se poursuivra en 2017<\/em><\/strong><em> afin d\u2019affiner la question des usages et de l\u2019am\u00e9nagement des espaces urbains.<\/em><\/p>\n<p style=\"text-align: justify;\">Pour avoir tous les d\u00e9tails de la concertation pr\u00e9alable voir <a href=\"http:\/\/www.lametro.fr\/TPL_CODE\/TPL_ACTUALITE\/PAR_TPL_IDENTIFIANT\/1572\/8-info-actualite-grenoble.htm\">ici<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sident de la M\u00e9tro, le pr\u00e9sident du Syndicat mixte des transports en commun (SMTC), le vice-pr\u00e9sident de la M\u00e9tropole d\u00e9l\u00e9gu\u00e9 aux espaces publics et \u00e0 la voirie et le maire de Grenoble, ont pr\u00e9sent\u00e9 le bilan de la concertation sur le projet CVCM (C\u0153urs de villes, c\u0153urs de m\u00e9tropole) qui va augmenter la pi\u00e9tonnisation [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[5,211],"class_list":["post-12460","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-deplacements","tag-modes-actifs"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/12460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=12460"}],"version-history":[{"count":1,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/12460\/revisions"}],"predecessor-version":[{"id":12462,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/12460\/revisions\/12462"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=12460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=12460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=12460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}