{"id":13079,"date":"2017-06-09T18:19:58","date_gmt":"2017-06-09T16:19:58","guid":{"rendered":"http:\/\/www.ades-grenoble.org\/wordpress\/?p=13079"},"modified":"2017-06-09T18:38:03","modified_gmt":"2017-06-09T16:38:03","slug":"des-indicateurs-du-bien-etre-soutenable-et-territorialise-ibest-pour-la-metropole","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2017\/06\/09\/des-indicateurs-du-bien-etre-soutenable-et-territorialise-ibest-pour-la-metropole\/","title":{"rendered":"Des indicateurs du bien \u00eatre soutenable et territorialis\u00e9 (IBEST) pour la m\u00e9tropole"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-13080 alignleft\" src=\"http:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/06\/IBEST-300x161.jpg\" alt=\"\" width=\"300\" height=\"161\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/06\/IBEST-300x161.jpg 300w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/06\/IBEST-150x81.jpg 150w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/06\/IBEST.jpg 409w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Une \u00e9quipe de chercheurs \u2013 \u00e9conomistes, sociologues, urbanistes, politistes, informaticiens\u2026\u00a0\u2013 r\u00e9unis autour du centre universitaire de recherche en \u00e9conomie de Grenoble (CREG) ont men\u00e9 un travail de recherche depuis plusieurs ann\u00e9es pour proposer aux acteurs de la m\u00e9tropole grenobloise de nouveaux indicateurs, alternatifs \u00e0 ceux classiquement utilis\u00e9s, permettant de saisir diff\u00e9rentes formes de bien-\u00eatre. Le rapport final de leurs recherches s\u2019intitule\u00a0: <em>\u00ab\u00a0Construction et repr\u00e9sentation des Indicateurs d\u2019un Bien-\u00catre Soutenable et Territorialis\u00e9 dans l\u2019agglom\u00e9ration grenobloise\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00ab\u00a0L\u2019exp\u00e9rimentation IBEST s\u2019inscrit dans le prolongement d\u2019une r\u00e9flexion men\u00e9e localement \u00e0 partir du rapport\u00a0<a href=\"http:\/\/www.ladocumentationfrancaise.fr\/rapports-publics\/024000191\/index.shtml\">Viveret<\/a>,\u00a0Reconsid\u00e9rer la richesse\u00a0(2001) critiquant les indicateurs classiques de mesure de la richesse (type PIB) et incitant \u00e0 mieux compter \u00ab\u00a0ce qui compte\u00a0\u00bb\u00a0\u2026<\/em><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><em>Cette r\u00e9flexion a fait largement \u00e9cho aux observations des intervenants dans le champ de la politique de la ville : les indicateurs sociaux traditionnels sont centr\u00e9s sur les difficult\u00e9s des personnes en termes de ch\u00f4mage, pr\u00e9carit\u00e9, d\u00e9linquance&#8230; Cette posture, qui permet de faire appara\u00eetre les disparit\u00e9s socio-spatiales, a des effets pervers bien connus depuis les politiques de zonage : la statistique dresse des rapports stigmatisant certains quartiers, omet une partie -positive- de la r\u00e9alit\u00e9, et surench\u00e9rit sur une image d\u00e9j\u00e0 n\u00e9gative des quartiers\u2026<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Le \u00ab\u00a0bien-\u00eatre\u00a0\u00bb renvoie \u00e0 la fois \u00e0 des notions subjectives, difficilement mesurables, mais aussi \u00e0 la notion plus quantifiable de ressources mobilisables par un individu pour bien vivre\u00a0: r\u00e9seaux et liens sociaux, solidarit\u00e9s de proximit\u00e9, capacit\u00e9 d&rsquo;agir, de s&rsquo;engager. Bien-\u00eatre \u00ab\u00a0soutenable\u00a0\u00bb ou \u00ab\u00a0durable\u00a0\u00bb parce que l&rsquo;id\u00e9e est que le bien-\u00eatre d&rsquo;un individu est aussi conditionn\u00e9 par sa capacit\u00e9 \u00e0 se projeter, \u00e0 s&rsquo;appuyer sur des ressources stables dans le temps\u2026<br \/>\n<\/em><\/p>\n<p style=\"text-align: justify;\">L\u2019IBEST fournit une nouvelle vision alternative du territoire en liant les enjeux sociaux aux enjeux environnementaux. Les indicateurs pris pour mesurer le bien-\u00eatre sont les suivants\u00a0:<\/p>\n<p style=\"text-align: justify;\"><em><u>Travail\/emploi<\/u><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li><em>Pourcentage\u00a0de\u00a0satisfaction\u00a0\u00e0\u00a0l\u2019\u00e9gard\u00a0de\u00a0son\u00a0travail\u00a0et\u00a0de\u00a0ses\u00a0conditions\u00a0d\u2019emploi<\/em><\/li>\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0exprimant\u00a0un\u00a0sentiment\u00a0de\u00a0justice\u00a0salariale\u00a0 <\/em><\/li>\n<li><em>Indice\u00a0d\u2019in\u00e9galit\u00e9\u00a0de\u00a0Gini <\/em><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><em><u>Affirmation\u00a0de\u00a0soi\u00a0et\u00a0engagement<\/u><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0d\u00e9clarant\u00a0avoir\u00a0le\u00a0sentiment\u00a0d\u2019avoir\u00a0le\u00a0contr\u00f4le\u00a0sur\u00a0leur\u00a0vie<\/em><\/li>\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0d\u00e9clarant\u00a0avoir\u00a0confiance\u00a0en\u00a0autrui<\/em><\/li>\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0ayant\u00a0plut\u00f4t\u00a0confiance\u00a0dans\u00a0le\u00a0syst\u00e8me\u00a0\u00e9ducatif\u00a0<\/em><\/li>\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0ayant\u00a0particip\u00e9\u00a0\u00e0\u00a0une\u00a0association\u00a0ou\u00a0\u00e0\u00a0une\u00a0mobilisation\u00a0collective\u00a0 <\/em><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><em><u>D\u00e9mocratie\u00a0et\u00a0vivre\u00a0ensemble\u00a0<\/u><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0d\u00e9clarant\u00a0avoir\u00a0plut\u00f4t\u00a0confiance\u00a0dans\u00a0les\u00a0institutions<\/em><\/li>\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0d\u00e9clarant\u00a0pouvoir\u00a0compter\u00a0sur\u00a0quelqu\u2019un\u00a0en\u00a0cas\u00a0de difficult\u00e9s<\/em><\/li>\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0ayant\u00a0au\u00a0moins\u00a0\u00e9t\u00e9\u00a0aid\u00e9es\u00a0ou\u00a0ayant\u00a0aid\u00e9\u00a0au\u00a0moins\u00a0une\u00a0fois\u00a0au\u00a0cours des six derniers\u00a0mois\u00a0 <\/em><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><em><u>Environnement\u00a0naturel\u00a0 <\/u><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0triant\u00a0toujours\u00a0leurs\u00a0d\u00e9chets\u00a0<\/em><\/li>\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0vivant\u00a0dans\u00a0un\u00a0logement\u00a0tr\u00e8s\u00a0bien\u00a0isol\u00e9<\/em><\/li>\n<li><em>Pourcentage\u00a0de\u00a0tests\u00a0positifs\u00a0concernant\u00a0la\u00a0qualit\u00e9\u00a0bact\u00e9riologique\u00a0de\u00a0l\u2019eau\u00a0de\u00a0consommation courante<\/em><\/li>\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0utilisant\u00a0un\u00a0mode\u00a0de\u00a0transport\u00a0\u00ab\u00a0doux\u00a0\u00bb\u00a0ou\u00a0\u00ab\u00a0semidoux\u00a0\u00bb\u00a0pour se rendre \u00e0 leur\u00a0travail\u00a0 <\/em><\/li>\n<li><em>Indice\u00a0de\u00a0la\u00a0qualit\u00e9\u00a0de\u00a0l\u2019air\u00a0<\/em><\/li>\n<li><em>Taux\u00a0d\u2019artificialisation\u00a0des\u00a0sols\u00a0<\/em><\/li>\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0trouvant\u00a0leur\u00a0quartier\u00a0pollu\u00e9\u00a0ou\u00a0sale\u00a0 <\/em><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><em><u>Sant\u00e9\u00a0 <\/u><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0peu\u00a0ou\u00a0pas\u00a0stress\u00e9es <\/em><\/li>\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0d\u00e9clarant\u00a0une\u00a0sant\u00e9\u00a0mauvaise\u00a0et non\u00a0suivies m\u00e9dicalement\u00a0 <\/em><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><em><u>Acc\u00e8s\u00a0et\u00a0recours\u00a0aux\u00a0services publics\u00a0 <\/u><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li><em>Pourcentage\u00a0de personnes\u00a0ayant\u00a0un acc\u00e8s\u00a0physique\u00a0facile\u00a0\u00e0\u00a0toutes\u00a0les\u00a0commodit\u00e9s<\/em><\/li>\n<li><em>Pourcentage\u00a0estim\u00e9\u00a0de\u00a0non\u00a0recours\u00a0aux\u00a0aides\u00a0sociales\u00a0 <\/em><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><em><u>Le\u00a0temps\u00a0et\u00a0le\u00a0rythme\u00a0de\u00a0vie<\/u><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0en\u00a0situation\u00a0d\u2019\u00e9quilibre\u00a0des\u00a0temps\u00a0d\u2019activit\u00e9<\/em><\/li>\n<li><em> Pourcentage\u00a0de\u00a0personnes\u00a0mettant\u00a0moins\u00a0d\u2019une\u00a0demi-heure\u00a0pour\u00a0se\u00a0rendre\u00a0\u00e0\u00a0leur\u00a0travail\u00a0 <\/em><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><em><u>L\u2019acc\u00e8s durable\u00a0aux\u00a0biens\u00a0de\u00a0 subsistance<\/u><\/em><em>\u00a0 <\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0vivant\u00a0dans\u00a0un\u00a0logement\u00a0non\u00a0suroccup\u00e9<\/em><\/li>\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0au\u2022dessus\u00a0du\u00a0seuil\u00a0de\u00a0pauvret\u00e9<\/em><\/li>\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0d\u00e9clarant\u00a0se\u00a0restreindre\u00a0sur\u00a0l\u2019alimentation<\/em><\/li>\n<li><em>Pourcentage\u00a0de\u00a0personnes\u00a0d\u00e9clarant\u00a0se\u00a0restreindre\u00a0sur\u00a0les\u00a0soins\u00a0m\u00e9dicaux<\/em><\/li>\n<li><em>Taux\u00a0d\u2019ad\u00e9quation\u00a0entre\u00a0l\u2019offre\u00a0et\u00a0la\u00a0demande\u00a0d\u2019h\u00e9bergement\u00a0social<\/em><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Les auteurs \u00e9valuent le niveau de bien \u00eatre pour la m\u00e9tropole \u00e0 0,633 et pour Grenoble \u00e0 0,631. Si un territoire atteignait l\u2019IBEST de 1, cela signifierait qu\u2019il est soutenable pour tous ses habitants. Le fait que le niveau de l\u2019IBEST soit quasi identique sur les territoires de l\u2019agglom\u00e9ration <em>\u00ab\u00a0permet de montrer\u00a0que\u00a0les\u00a0territoires\u00a0sont\u00a0confront\u00e9s\u00a0\u00e0\u00a0des\u00a0enjeux\u00a0communs,\u00a0puisqu\u2019ils\u00a0sont\u00a0tous\u00a0dans\u00a0une situation interm\u00e9diaire en termes\u00a0de bien \u00eatre soutenable et \u00e9vite une mise en concurrence des territoires entre eux via la comparaison.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>L\u2019indicateur\u00a0est\u00a0donc\u00a0tourn\u00e9\u00a0vers\u00a0les\u00a0changements\u00a0\u00e0\u00a0op\u00e9rer\u00a0dans la perspective de la transition \u00e9cologique et sociale, ce qui constitue un atout d\u2019un point de vue op\u00e9rationnel et\u00a0communicationnel.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">Le rapport peut \u00eatre t\u00e9l\u00e9charg\u00e9 en deux parties : <a href=\"http:\/\/bienetre.lametro.fr\/PDF\/Rapport_IBEST_HD_sans_traits_de_coupe_partie_1.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">ici<\/a> et <a href=\"http:\/\/bienetre.lametro.fr\/PDF\/Rapport_IBEST_HD_sans_traits_de_coupe_partie_2.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">l\u00e0<\/a>.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Une \u00e9quipe de chercheurs \u2013 \u00e9conomistes, sociologues, urbanistes, politistes, informaticiens\u2026\u00a0\u2013 r\u00e9unis autour du centre universitaire de recherche en \u00e9conomie de Grenoble (CREG) ont men\u00e9 un travail de recherche depuis plusieurs ann\u00e9es pour proposer aux acteurs de la m\u00e9tropole grenobloise de nouveaux indicateurs, alternatifs \u00e0 ceux classiquement utilis\u00e9s, permettant de saisir diff\u00e9rentes formes de bien-\u00eatre. Le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[32,33],"class_list":["post-13079","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-metro","tag-social"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/13079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=13079"}],"version-history":[{"count":1,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/13079\/revisions"}],"predecessor-version":[{"id":13081,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/13079\/revisions\/13081"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=13079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=13079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=13079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}