{"id":13328,"date":"2017-09-15T14:50:25","date_gmt":"2017-09-15T12:50:25","guid":{"rendered":"http:\/\/www.ades-grenoble.org\/wordpress\/?p=13328"},"modified":"2017-09-15T14:52:16","modified_gmt":"2017-09-15T12:52:16","slug":"agenda-58","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2017\/09\/15\/agenda-58\/","title":{"rendered":"Agenda"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13329 alignleft\" src=\"http:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/09\/tour-perret-illumination.jpg\" alt=\"\" width=\"350\" height=\"162\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/09\/tour-perret-illumination.jpg 350w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/09\/tour-perret-illumination-150x69.jpg 150w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/09\/tour-perret-illumination-300x139.jpg 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/>Samedi 16 septembre \u00e0 20 h, mise en lumi\u00e8re de la Tour Perret<\/strong>, dans le cadre des journ\u00e9es europ\u00e9ennes du patrimoine. L\u2019IUT1 de l\u2019Universit\u00e9 Grenoble Alpes a r\u00e9alis\u00e9 un syst\u00e8me de programmation lumineuse \u00e0 distance qui sera pr\u00e9sent\u00e9 au pied de la Tour.<\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><strong>Mardi 19 septembre \u00e0 19 heures,\u00a0conf\u00e9rence de Benjamin Stora<\/strong> <strong>\u00a0\u00bb Questions autour de l&rsquo;Histoire de l&rsquo;immigration \u00ab\u00a0.<\/strong> Au Centre \u0152cum\u00e9nique Saint-Marc de Grenoble (6, avenue Malherbe, 38100 Grenoble). Benjamin Stora est historien, professeur \u00e0 l&rsquo;universit\u00e9, pr\u00e9sident du conseil d&rsquo;orientation du Mus\u00e9e National de l&rsquo;Histoire de l&rsquo;Immigration, auteur de nombreux ouvrages. La Conf\u00e9rence est organis\u00e9e par l&rsquo;association<strong>\u00a0ATLLAS <\/strong>(Association tisser les liens d&rsquo;amiti\u00e9s solidaires)<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>Vendredi 22 septembre et samedi 23 \u00e0 l\u2019ODTI place Edmond Arnaud, 9<sup>\u00e8me<\/sup> \u00e9dition d\u2019Equinox M\u00e8tis.<\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li>Vendredi de 18 h \u00e0 20 h, d\u00e9bat sur le th\u00e8me\u00a0: \u00ab Migrant-es et diasporas\u00a0: comment fait l\u2019Allemagne, ses l\u00e4nder et ses communes\u00a0?\u00a0\u00bb<\/li>\n<li>Samedi 12 h, couscous r\u00e9publicain communautaire (poulet-riz) avec des recettes de pays diff\u00e9rents. A 13 h 30 inauguration de l\u2019installation des droits de l\u2019homme et du citoyen du 26 ao\u00fbt 1789 et l\u2019association GOSPEL INSTITUT donnera un concert en plein air.<\/li>\n<\/ul>\n<hr \/>\n<p style=\"text-align: justify;\"><strong>Samedi 23 septembre de 10 h \u00e0 minuit, \u00ab\u00a0<em>la F\u00eate des Possibles\u00a0: cr\u00e9ons demain pr\u00e8s de chez nous<\/em>\u00a0\u00bb, place Victor Hugo et Parc Paul Mistral<\/strong>. Voir <a href=\"https:\/\/alternatiba.eu\/grenoble\/fete-possibles-2017\/\" target=\"_blank\" rel=\"noopener\">ici<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Samedi 16 septembre \u00e0 20 h, mise en lumi\u00e8re de la Tour Perret, dans le cadre des journ\u00e9es europ\u00e9ennes du patrimoine. L\u2019IUT1 de l\u2019Universit\u00e9 Grenoble Alpes a r\u00e9alis\u00e9 un syst\u00e8me de programmation lumineuse \u00e0 distance qui sera pr\u00e9sent\u00e9 au pied de la Tour. Mardi 19 septembre \u00e0 19 heures,\u00a0conf\u00e9rence de Benjamin Stora \u00a0\u00bb Questions autour [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[125],"class_list":["post-13328","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-agenda"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/13328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=13328"}],"version-history":[{"count":1,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/13328\/revisions"}],"predecessor-version":[{"id":13330,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/13328\/revisions\/13330"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=13328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=13328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=13328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}