{"id":14290,"date":"2018-05-11T14:26:57","date_gmt":"2018-05-11T12:26:57","guid":{"rendered":"http:\/\/www.ades-grenoble.org\/wordpress\/?p=14290"},"modified":"2018-05-11T15:00:55","modified_gmt":"2018-05-11T13:00:55","slug":"mal-logement-mal-loges-le-rapport-de-lonpes","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2018\/05\/11\/mal-logement-mal-loges-le-rapport-de-lonpes\/","title":{"rendered":"\u00ab Mal-logement, Mal-log\u00e9s \u00bb, le rapport de l\u2019ONPES"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9875 alignleft\" src=\"http:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2015\/03\/ONPES.jpg\" alt=\"\" width=\"471\" height=\"165\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2015\/03\/ONPES.jpg 471w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2015\/03\/ONPES-150x53.jpg 150w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2015\/03\/ONPES-300x105.jpg 300w\" sizes=\"auto, (max-width: 471px) 100vw, 471px\" \/>L\u2019observatoire national de la pauvret\u00e9 et de l\u2019exclusion sociale (ONPES) publie le 2 mai son rapport annuel 2017-2018, intitul\u00e9 \u00ab <em>Mal-logement, Mal-log\u00e9s<\/em> \u00bb.<\/p>\n<p style=\"text-align: justify;\">L\u2019Observatoire national de la pauvret\u00e9 et de l\u2019exclusion sociale a \u00e9t\u00e9 cr\u00e9\u00e9 en 1998 par la loi\u00a0relative \u00e0 la lutte contre les exclusions, en r\u00e9ponse \u00e0 une demande des associations \u0153uvrant dans le champ de la lutte contre les exclusions.<\/p>\n<p style=\"text-align: justify;\"><em>\u00ab\u00a0Les explorations men\u00e9es dans le cadre de la r\u00e9alisation de ce rapport r\u00e9v\u00e8lent notamment deux degr\u00e9s d\u2019intensit\u00e9 dans les situations de mal-logement\u00a0:<br \/>\nUne charge excessive en logement pour les m\u00e9nages, qui entra\u00eene des privations sur les autres besoins \u00e0 satisfaire, compromet la participation \u00e0 la vie sociale, et qui touche une part croissante des m\u00e9nages \u00e0 faibles revenus\u00a0;<br \/>\nLa difficult\u00e9 rencontr\u00e9e par les personnes de passer d\u2019une situation marginale de logement (ex\u00a0: la privation de domicile personnel) \u00e0 une situation de logement de droit commun.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>L\u2019un et l\u2019autre posent plus g\u00e9n\u00e9ralement la question de l\u2019insuffisance d\u2019une offre de logements abordables dans certains territoires, sp\u00e9cialement les plus urbains.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Voici le communiqu\u00e9 pr\u00e9sentant le rapport\u00a0:<\/p>\n<p style=\"text-align: justify;\"><em>\u00ab\u00a0En soixante ans, les conditions de logement n\u2019ont cess\u00e9 de s\u2019am\u00e9liorer gr\u00e2ce \u00e0 un effort sans pr\u00e9c\u00e9dent de construction et de r\u00e9novation de l\u2019habitat encourag\u00e9 par les pouvoirs publics. Aujourd\u2019hui, pratiquement tous les logements disposent du confort le plus \u00e9l\u00e9mentaire, comme le chauffage ou les \u00e9quipements sanitaires. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Pour autant, les standards du confort, en \u00e9voluant, sont devenus plus exigeants alors que l\u2019ensemble de la population n\u2019y a pas encore acc\u00e8s. R\u00e9cemment le rapport annuel de la Fondation Abb\u00e9 Pierre sur \u00ab l\u2019\u00e9tat du mal-logement en France \u00bb nous a alert\u00e9s sur \u00ab le d\u00e9crochage des couches populaires et l\u2019in\u00e9galit\u00e9 de leurs destins r\u00e9sidentiels \u00bb. Les situations de logement actuelles des m\u00e9nages les plus modestes doivent ainsi s\u2019appr\u00e9hender dans le temps long, au prisme de la fin des Trente Glorieuses, des retomb\u00e9es de la \u00ab nouvelle pauvret\u00e9 \u00bb qui a \u00e9merg\u00e9 au cours des ann\u00e9es 1980, puis de la crise \u00e9conomique et sociale de 2008, d\u2019une s\u00e9v\u00e9rit\u00e9 in\u00e9dite, et enfin au regard des migrations r\u00e9centes. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>De nombreux foyers ont des difficult\u00e9s \u00e0 joindre les deux bouts une fois le loyer r\u00e9gl\u00e9. Les files d\u2019attente pour acc\u00e9der \u00e0 un logement social dans les zones tendues, et donc les plus ch\u00e8res, sont longues. Dans certains territoires, l\u2019habitat informel et pr\u00e9caire s\u2019enracine. L\u2019acc\u00e8s \u00e0 la propri\u00e9t\u00e9 est devenu hors d\u2019atteinte pour les plus modestes, dessinant l\u00e0 une ligne de fracture entre les cat\u00e9gories sociales. Il est d\u00e9sormais fr\u00e9quent de croiser dans les grandes agglom\u00e9rations des personnes durablement d\u00e9pourvues d\u2019un domicile. Caract\u00e9ris\u00e9e hier par le d\u00e9ficit de logement et leur insalubrit\u00e9, la crise du logement se d\u00e9voile \u00e0 pr\u00e9sent plus diffuse et prot\u00e9iforme. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>En se concentrant sur la situation des m\u00e9nages pauvres et modestes, l\u2019Onpes livre un travail approfondi sur ce que signifie pour eux d\u2019\u00eatre mal log\u00e9s dans la France d\u2019aujourd\u2019hui. Le rapport s\u2019ouvre sur une pr\u00e9sentation de la m\u00e9thode de l\u2019observatoire pour qualifier son approche du \u00ab mal-logement \u00bb. L\u2019analyse des conditions de logement et d\u2019habitat des populations pauvres et aux ressources modestes est aussi \u00e9clair\u00e9e par la perception qu\u2019elles en ont et les risques sanitaires et sociaux encourus. Le rapport explore \u00e9galement les situations les plus graves de mal-logement, aux marges du logement de droit commun, l\u00e0 o\u00f9 la connaissance de l\u2019habitat critique est souvent parcellaire. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Finalement, les r\u00e9sultats r\u00e9v\u00e8lent deux seuils qui bornent le mal-logement : un seuil au-dessus duquel la charge en logement devient excessive, entra\u00eenant des privations sur les autres besoins \u00e0 satisfaire, compromettant la participation \u00e0 la vie sociale, et qui touche une part croissante des m\u00e9nages \u00e0 faibles revenus ; un seuil associ\u00e9 aux situations marginales de logement, rudes et expos\u00e9es, dont l\u2019issue est complexe et incertaine. L\u2019un et l\u2019autre posent plus g\u00e9n\u00e9ralement la question de l\u2019insuffisance d\u2019une offre de logements abordables dans certains territoires, sp\u00e9cialement les plus urbains. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Dans cet ouvrage, le mal-logement et les mal-log\u00e9s se donnent \u00e0 voir dans la France contemporaine, aux contrastes parfois saisissants, symptomatiques des formes actuelles de pr\u00e9carit\u00e9 sociale.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Pour lire le rapport\u00a0: <a href=\"http:\/\/www.onpes.gouv.fr\/rapport-onpes-2017-2018-mal-logement-mal-loges.html\">http:\/\/www.onpes.gouv.fr\/rapport-onpes-2017-2018-mal-logement-mal-loges.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019observatoire national de la pauvret\u00e9 et de l\u2019exclusion sociale (ONPES) publie le 2 mai son rapport annuel 2017-2018, intitul\u00e9 \u00ab Mal-logement, Mal-log\u00e9s \u00bb. L\u2019Observatoire national de la pauvret\u00e9 et de l\u2019exclusion sociale a \u00e9t\u00e9 cr\u00e9\u00e9 en 1998 par la loi\u00a0relative \u00e0 la lutte contre les exclusions, en r\u00e9ponse \u00e0 une demande des associations \u0153uvrant dans [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[181,33],"class_list":["post-14290","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-precarite","tag-social"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/14290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=14290"}],"version-history":[{"count":1,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/14290\/revisions"}],"predecessor-version":[{"id":14291,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/14290\/revisions\/14291"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=14290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=14290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=14290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}