{"id":14292,"date":"2018-05-11T14:32:58","date_gmt":"2018-05-11T12:32:58","guid":{"rendered":"http:\/\/www.ades-grenoble.org\/wordpress\/?p=14292"},"modified":"2018-05-11T15:01:02","modified_gmt":"2018-05-11T13:01:02","slug":"consultation-nationale-sur-villes-et-territoires-de-demain","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2018\/05\/11\/consultation-nationale-sur-villes-et-territoires-de-demain\/","title":{"rendered":"Consultation nationale sur \u00ab Villes et Territoires de demain \u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-14293 alignleft\" src=\"http:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2018\/05\/Villes-demain.jpg\" alt=\"\" width=\"400\" height=\"56\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2018\/05\/Villes-demain.jpg 400w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2018\/05\/Villes-demain-150x21.jpg 150w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2018\/05\/Villes-demain-300x42.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Les minist\u00e8res de la Transition \u00e9cologique et solidaire et de la Coh\u00e9sion des territoires lancent une consultation citoyenne intitul\u00e9e \u00ab\u00a0Villes et territoires de demain\u00a0\u00bb du 2 mai au 17 juillet 2018.<\/p>\n<p style=\"text-align: justify;\">Cette consultation-d\u00e9bat est organis\u00e9e <a href=\"http:\/\/www.contributions-villesterritoires.gouv.fr\" target=\"_blank\" rel=\"noopener\">en ligne<\/a> autour de cinq th\u00e9matiques : habiter son quartier, se d\u00e9placer, participer \u00e0 la vie locale, vivre en bonne sant\u00e9 et se former et travailler. Sur chacun de ces sujets, des \u00e9l\u00e9ments de contexte sont indiqu\u00e9s et une charte de la participation pr\u00e9cise les r\u00e8gles du d\u00e9bat et de la consultation.<\/p>\n<p style=\"text-align: justify;\">Extraits du communiqu\u00e9 du 3 mai 2018\u00a0des deux minist\u00e8res :<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><em>L\u2019objectif est de co-\u00e9laborer des \u00ab Livrets citoyens \u00bb pour guider les politiques publiques. Dans les ann\u00e9es qui viennent, nos villes et nos territoires vont conna\u00eetre de profonds bouleversements : transformation num\u00e9rique, vieillissement de la population, changement climatique, \u00e9rosion de la biodiversit\u00e9, etc. Pour relever ces d\u00e9fis, nous avons besoin d\u2019une r\u00e9flexion commune. La consultation num\u00e9rique qui s\u2019ouvre a pour but de donner la parole \u00e0 l\u2019ensemble des citoyens pour construire une vision des \u00ab Villes et territoires de demain \u00bb. Tous les internautes sont invit\u00e9s \u00e0 partager leurs id\u00e9es, leurs attentes et leurs solutions. Modalit\u00e9s de la consultation La consultation s\u2019articule autour de 5 th\u00e9matiques : &#8211; habiter son quartier, &#8211; se d\u00e9placer, &#8211; participer \u00e0 la vie locale, &#8211; vivre en bonne sant\u00e9, &#8211; se former et travailler. Chacun de ces th\u00e8mes sera mis en d\u00e9bat au cours de quatre temps successifs : <\/em><\/p>\n<ul>\n<li style=\"text-align: justify;\"><em>du 2 au 22 mai, une phase de recueil des attentes et de d\u00e9finition des d\u00e9fis de demain ; <\/em><\/li>\n<li style=\"text-align: justify;\"><em>du 23 mai au 19 juin, une \u00e9tape de co-construction des solutions concr\u00e8tes ; <\/em><\/li>\n<li style=\"text-align: justify;\"><em>du 20 juin au 10 juillet, un temps d\u2019approfondissement des projets les plus discut\u00e9s de la phase 2 ; <\/em><\/li>\n<li style=\"text-align: justify;\"><em>enfin du 11 au 17 juillet, une phase de vote. <\/em><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><em>La consultation permettra de faire \u00e9merger les priorit\u00e9s des citoyens en mati\u00e8re de coh\u00e9sion territoriale et de d\u00e9veloppement durable. Les Livrets citoyens cr\u00e9\u00e9s auront vocation \u00e0 devenir une r\u00e9f\u00e9rence, mise \u00e0 disposition des services de l\u2019\u00c9tat, des collectivit\u00e9s et plus largement des acteurs des villes et territoires pour b\u00e2tir des politiques nationales et locales en ad\u00e9quation avec les attentes exprim\u00e9es. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Par ailleurs, il est propos\u00e9 aux citoyens de r\u00e9diger des sc\u00e9narios d\u00e9crivant leur vie dans les villes et territoires de demain. Les meilleurs seront adapt\u00e9s en bande dessin\u00e9e. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Retrouvez en ligne la plateforme ici.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les minist\u00e8res de la Transition \u00e9cologique et solidaire et de la Coh\u00e9sion des territoires lancent une consultation citoyenne intitul\u00e9e \u00ab\u00a0Villes et territoires de demain\u00a0\u00bb du 2 mai au 17 juillet 2018. Cette consultation-d\u00e9bat est organis\u00e9e en ligne autour de cinq th\u00e9matiques : habiter son quartier, se d\u00e9placer, participer \u00e0 la vie locale, vivre en bonne [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[11],"tags":[300,196],"class_list":["post-14292","post","type-post","status-publish","format-standard","hentry","category-politique-locale","tag-democratie","tag-etat"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/14292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=14292"}],"version-history":[{"count":1,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/14292\/revisions"}],"predecessor-version":[{"id":14294,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/14292\/revisions\/14294"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=14292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=14292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=14292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}