{"id":15768,"date":"2019-05-03T13:59:46","date_gmt":"2019-05-03T11:59:46","guid":{"rendered":"http:\/\/www.ades-grenoble.org\/wordpress\/?p=15768"},"modified":"2019-05-03T14:20:23","modified_gmt":"2019-05-03T12:20:23","slug":"nouvel-accord-sur-les-hlm-une-fausse-bonne-solution","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2019\/05\/03\/nouvel-accord-sur-les-hlm-une-fausse-bonne-solution\/","title":{"rendered":"Nouvel accord sur les HLM, une fausse bonne solution"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"265\" src=\"http:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/10\/matignon.jpg\" alt=\"\" class=\"wp-image-13511\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/10\/matignon.jpg 400w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/10\/matignon-150x99.jpg 150w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/10\/matignon-300x199.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Devant la mobilisation des \u00e9lus locaux et des\nbailleurs sociaux, le gouvernement a l\u00e9g\u00e8rement recul\u00e9 sur la diminution programm\u00e9e\ndes ressources des bailleurs sociaux \u00e0 partir de 2020. Il \u00e9tait pr\u00e9vu de multiplier\npar deux la diminution des APL pour les locataires en logement social afin d\u2019\u00e9conomiser\n1,5 milliards d\u2019euros dans le budget de l\u2019Etat \u00e0 partir de 2020. Actuellement cette\nponction qui a d\u00e9marr\u00e9 en 2018 est de 800 millions d\u2019euros. A partir de 2020 ce\nsera 1,3 milliards d\u2019euros. Pour \u00e9viter que les locataires ne soient punis directement,\nle gouvernement impose une diminution de loyer aux organismes HLM du montant de\nla r\u00e9duction des APL, c\u2019est le fameux RLS (r\u00e9duction de loyer de solidarit\u00e9).\nDonc ce sont les bailleurs sociaux qui voient leurs ressources fortement\ndiminu\u00e9es et pour ceux qui ont beaucoup de locataires avec APL (notamment dans\nles quartiers de la politique de la ville), la punition est tr\u00e8s s\u00e9v\u00e8re.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les bailleurs sociaux (dont les finances d\u00e9pendent\nen presque totalit\u00e9 des loyers) sont oblig\u00e9s de diminuer leurs services, leurs\nr\u00e9novations et m\u00eame leurs constructions.<\/p>\n\n\n<p><!--more--><\/p>\n\n\n<p class=\"wp-block-paragraph\">Un accord qui vient d\u2019\u00eatre sign\u00e9 entre le gouvernement\net l\u2019USH (Union Sociale de l\u2019Habitat, repr\u00e9sentant l\u2019ensemble des bailleurs)\npr\u00e9voit la ponction de 1,3 milliards par le RLS \u00e0 partir de 2020, mais pour\natt\u00e9nuer la purge le gouvernement a propos\u00e9 que les bailleurs diminuent de 300\nmillions d\u2019euros les cotisations des organismes HLM au Fnap (fonds national des\naides \u00e0 la pierre) et 50 millions de remises sur les int\u00e9r\u00eats de la dette des\norganismes aupr\u00e8s de la Caisse des D\u00e9p\u00f4ts. Cela diminue d\u2019autant le budget du\nFnap, qui apportait des aides <em>\u00ab&nbsp;<\/em><em>au&nbsp;financement des op\u00e9rations\nde d\u00e9veloppement, d&rsquo;am\u00e9lioration et de d\u00e9molition du parc de logements locatifs\nsociaux appartenant aux organismes d&rsquo;habitations \u00e0 loyer mod\u00e9r\u00e9&nbsp;\u00bb<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces 300 millions vont manquer un moment ou \u00e0 un\nautre au d\u00e9veloppement du logement social&nbsp;! Cette r\u00e9duction sera compens\u00e9e\npar Action logement (l\u2019ex 1% patronal) donc qui investira moins pour le\nlogement social dans les projets Anru, dont il est le principal financeur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Il y aura aussi\nune att\u00e9nuation de l\u2019augmentation de la TVA qui est pass\u00e9e \u00e0 10 % pour les op\u00e9rations\nde construction et de r\u00e9novation alors que pr\u00e9c\u00e9demment elle \u00e9tait seulement de\n5,5%. Le maintien de la TVA \u00e0 5,5% sera uniquement\npour certaines op\u00e9rations : les PLAI (logements tr\u00e8s sociaux), les op\u00e9rations men\u00e9es\ndans le cadre de l\u2019Anru et dans les logements PLUS en acquisition-am\u00e9lioration.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En conclusion l\u2019USH a sign\u00e9 l\u2019accord mais pr\u00e9cise\nqu\u2019il ne s\u2019agit pas d\u2019une approbation et poursuit ses demandes de remise en\ncause du RLS et de l\u2019augmentation de la TVA.\n\nDans l\u2019agglom\u00e9ration, la M\u00e9tro\net la Ville de Grenoble ont bien raison de restructurer l\u2019op\u00e9rateur de logement\nsocial de la M\u00e9tropole en organisant la fusion ACTIS-GH afin de trouver un\nmod\u00e8le \u00e9conomique qui sauvera l\u2019\u00e9quilibre financier du nouvel op\u00e9rateur et le\ncontr\u00f4le de ce dernier par les collectivit\u00e9s publiques locales.\n\n\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Devant la mobilisation des \u00e9lus locaux et des bailleurs sociaux, le gouvernement a l\u00e9g\u00e8rement recul\u00e9 sur la diminution programm\u00e9e des ressources des bailleurs sociaux \u00e0 partir de 2020. Il \u00e9tait pr\u00e9vu de multiplier par deux la diminution des APL pour les locataires en logement social afin d\u2019\u00e9conomiser 1,5 milliards d\u2019euros dans le budget de l\u2019Etat [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[196,138,66,33],"class_list":["post-15768","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-etat","tag-finances","tag-logement","tag-social"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/15768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=15768"}],"version-history":[{"count":1,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/15768\/revisions"}],"predecessor-version":[{"id":15769,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/15768\/revisions\/15769"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=15768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=15768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=15768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}