{"id":16354,"date":"2019-10-18T15:05:44","date_gmt":"2019-10-18T13:05:44","guid":{"rendered":"http:\/\/www.ades-grenoble.org\/wordpress\/?p=16354"},"modified":"2019-10-18T17:15:15","modified_gmt":"2019-10-18T15:15:15","slug":"les-inegalites-auraient-augmente-en-2018-en-france","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2019\/10\/18\/les-inegalites-auraient-augmente-en-2018-en-france\/","title":{"rendered":"Les in\u00e9galit\u00e9s auraient augment\u00e9 en 2018 en France"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"307\" height=\"407\" src=\"http:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2019\/10\/inegalites-sociales.png\" alt=\"\" class=\"wp-image-16355\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2019\/10\/inegalites-sociales.png 307w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2019\/10\/inegalites-sociales-113x150.png 113w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2019\/10\/inegalites-sociales-226x300.png 226w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/><\/figure><\/div>\n\n\n\n<p>Le 16 octobre 2019, l\u2019INSEE\ndonne une estimation de l\u2019\u00e9volution d\u2019un des indicateurs d\u2019in\u00e9galit\u00e9s, l\u2019indice\nde Gini. Cet indice augmenterait de mani\u00e8re significative et cette augmentation\nserait la plus importante depuis 2010. Ceci proviendrait de l\u2019augmentation des\nrevenus des plus riches. <\/p>\n\n\n\n<p>Selon\nla d\u00e9finition de l\u2019INSEE&nbsp;: <em>\u00ab&nbsp;l&rsquo;indice (ou coefficient) de Gini est\nun indicateur synth\u00e9tique d&rsquo;in\u00e9galit\u00e9s de salaires (de revenus, de niveaux de\nvie&#8230;). Il&nbsp;varie entre 0 et 1. Il est \u00e9gal \u00e0 0 dans une situation\nd&rsquo;\u00e9galit\u00e9 parfaite o\u00f9 tous les salaires, les revenus, les niveaux de vie&#8230;\nseraient \u00e9gaux. A l&rsquo;autre extr\u00eame, il est \u00e9gal \u00e0 1 dans une situation la plus\nin\u00e9galitaire possible, celle o\u00f9 tous les salaires (les revenus, les niveaux de\nvie&#8230;) sauf un seraient nuls. Entre 0 et 1, l&rsquo;in\u00e9galit\u00e9 est d&rsquo;autant plus\nforte que l&rsquo;indice de Gini est \u00e9lev\u00e9.<\/em><\/p>\n\n\n\n<p>Le r\u00e9sum\u00e9 de l\u2019\u00e9tude de l\u2019INSEE&nbsp;:<\/p>\n\n\n\n<p><strong><em>\u00ab&nbsp;Estimation\navanc\u00e9e du taux de pauvret\u00e9 et des indicateurs d\u2019in\u00e9galit\u00e9s<\/em><\/strong><\/p>\n\n\n<p><!--more--><\/p>\n\n\n<p><em>En 2018, les in\u00e9galit\u00e9s et\nle taux de pauvret\u00e9 augmenteraient<\/em><\/p>\n\n\n\n<p><em>Selon la m\u00e9thode\nd\u2019estimation avanc\u00e9e bas\u00e9e sur la microsimulation, les in\u00e9galit\u00e9s de niveau de\nvie augmenteraient en 2018&nbsp;: l\u2019indice de Gini augmenterait de 0,005 pour\ns\u2019\u00e9tablir \u00e0 0,294 et le ratio entre la masse des niveaux de vie d\u00e9tenue par les\n20&nbsp;% de personnes les plus ais\u00e9es et celle d\u00e9tenue par les 20&nbsp;% les\nplus modestes augmenterait de 0,1 pour s\u2019\u00e9tablir \u00e0 4,4. Le rapport interd\u00e9cile\nserait quasi stable \u00e0 3,5. La hausse des in\u00e9galit\u00e9s serait surtout li\u00e9e \u00e0 la forte\naugmentation des revenus des capitaux mobiliers d\u00e9sormais soumis au pr\u00e9l\u00e8vement\nforfaitaire unique, concentr\u00e9s chez les plus ais\u00e9s.<\/em><\/p>\n\n\n\n<p><em>Le taux de pauvret\u00e9\naugmenterait de 0,6&nbsp;point en 2018, pour atteindre 14,7&nbsp;% de la\npopulation. Cette hausse s\u2019expliquerait en partie par la diminution des\nallocations logement dans le parc HLM en 2018, les niveaux de vie n\u2019int\u00e9grant\npas la baisse de loyer \u00e9quivalente. En neutralisant l\u2019effet de la baisse des\nallocations logement dans le parc social, cette hausse serait plus mod\u00e9r\u00e9e (+&nbsp;0,2&nbsp;point).&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p>Voir l&rsquo;\u00e9tude de l&rsquo;INSEE <a rel=\"noreferrer noopener\" aria-label=\"ici (s\u2019ouvre dans un nouvel onglet)\" href=\"https:\/\/www.insee.fr\/fr\/statistiques\/4231288\" target=\"_blank\">ici<\/a> et l&rsquo;article suivant.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 16 octobre 2019, l\u2019INSEE donne une estimation de l\u2019\u00e9volution d\u2019un des indicateurs d\u2019in\u00e9galit\u00e9s, l\u2019indice de Gini. Cet indice augmenterait de mani\u00e8re significative et cette augmentation serait la plus importante depuis 2010. Ceci proviendrait de l\u2019augmentation des revenus des plus riches. Selon la d\u00e9finition de l\u2019INSEE&nbsp;: \u00ab&nbsp;l&rsquo;indice (ou coefficient) de Gini est un indicateur synth\u00e9tique [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[298,285,181,33],"class_list":["post-16354","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-france","tag-insee","tag-precarite","tag-social"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/16354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=16354"}],"version-history":[{"count":2,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/16354\/revisions"}],"predecessor-version":[{"id":16357,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/16354\/revisions\/16357"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=16354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=16354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=16354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}