{"id":16579,"date":"2019-12-06T14:24:09","date_gmt":"2019-12-06T13:24:09","guid":{"rendered":"https:\/\/www.ades-grenoble.org\/wordpress\/?p=16579"},"modified":"2019-12-06T15:40:40","modified_gmt":"2019-12-06T14:40:40","slug":"financement-du-logement-social-attention-danger","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2019\/12\/06\/financement-du-logement-social-attention-danger\/","title":{"rendered":"Financement du logement social, attention danger !"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"421\" height=\"116\" src=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/02\/USH.jpg\" alt=\"\" class=\"wp-image-12625\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/02\/USH.jpg 421w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/02\/USH-150x41.jpg 150w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/02\/USH-300x83.jpg 300w\" sizes=\"auto, (max-width: 421px) 100vw, 421px\" \/><\/figure><\/div>\n\n\n\n<p>Datant\nde juillet 2019, mais publi\u00e9 seulement en novembre, un rapport intitul\u00e9 \u00ab&nbsp;<em>La\ndiversification des sources de financement du secteur du logement locatif social&nbsp;<\/em>\u00bb\na \u00e9t\u00e9 r\u00e9alis\u00e9 par l\u2019inspection G\u00e9n\u00e9rale des finances (IGF) et le Conseil\nG\u00e9n\u00e9ral de l\u2019environnement et du d\u00e9veloppement durable (CGEDD). Il s\u2019interroge\nnotamment sur la mobilisation des capitaux priv\u00e9s pour\nfinancer le logement social en France.<\/p>\n\n\n\n<p>Ces interrogations deviennent plus pr\u00e9gnantes vu des difficult\u00e9s que\nconnait le secteur depuis la violente agression que les bailleurs subissent\n(surtout ceux en QPV) et la cr\u00e9ation d\u00e9but 2018 de la r\u00e9duction du loyer de\nsolidarit\u00e9 (RLS) qui accompagne la diminution des APL pour les locataires du\nlogement social. La politique Macron a \u00e9t\u00e9 clairement explicit\u00e9 par le\nPr\u00e9sident d\u00e8s fin 2017 et se met inexorablement \u00ab&nbsp;en marche&nbsp;\u00bb&nbsp;:\nfaire des \u00e9conomies pour le budget de l\u2019Etat en diminuant le poids de APL,\ndiminuer le nombre de bailleurs, pas de bailleurs de moins de 12000 logements\nen fin 2020 (ACTIS est particuli\u00e8rement concern\u00e9 puisqu\u2019il est pass\u00e9 sous ce\nseuil) et financiariser ce secteur du logement et y faire p\u00e9n\u00e9trer de puissants\nint\u00e9r\u00eat priv\u00e9s qui viendront au secours de ce secteur asphyxi\u00e9 financi\u00e8rement. Il\nest en effet \u00e9vident que les\nlogements sociaux ont une valeur \u00e9conomique bien sup\u00e9rieure \u00e0 celle inscrite au\nbilan des bailleurs et cela attire des convoitises et certains \u00e9lus peu\nregardants sur le patrimoine public (comme l\u2019ancien maire corrompu de Grenoble)\npourraient c\u00e9der aux sir\u00e8nes financi\u00e8res d\u2019autant plus que les collectivit\u00e9s\nsont asphyxi\u00e9es financi\u00e8rement par les politiques gouvernementales successives.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>M\u00eame si\nce rapport d\u00e9fend l\u2019int\u00e9r\u00eat public du logement social, il a \u00e9t\u00e9 missionn\u00e9 pour\n\u00e9tudier la p\u00e9n\u00e9tration de capitaux priv\u00e9s sous diverses formes. On peut y\nlire&nbsp;: \u00ab&nbsp;\u2026 <em>le maintien dans les ann\u00e9es \u00e0 venir d\u2019objectifs de\nconstruction ambitieux, notamment en zone \u00ab tendue \u00bb, suppose un renforcement\ndes fonds propres des organismes et pose la question de l\u2019irruption de\ncapitaux priv\u00e9s.<\/em>&nbsp;\u00bb<\/p>\n\n\n\n<p>Ce qui\ninqui\u00e8te l\u2019USH (Union Sociale pour l\u2019Habitat) qui appelle le gouvernement\n\u00e0 sortir du double jeu dans un communiqu\u00e9 du 21 novembre&nbsp;:<\/p>\n\n\n\n<p><em>\u00ab&nbsp;L\u2019Union sociale pour l\u2019habitat a\npris connaissance aujourd\u2019hui, par voie de presse, du rapport command\u00e9 par le\nGouvernement \u00e0 l\u2019Inspection G\u00e9n\u00e9rale des Finances (IGF) et au Conseil g\u00e9n\u00e9ral\nde l\u2019Environnement et du D\u00e9veloppement durable (CGEDD), dat\u00e9 de juillet 2019,\net intitul\u00e9 \u00ab La diversification des sources de financement du logement social\n\u00bb. Ce rapport pr\u00e9sente un certain nombre d\u2019options qui viseraient \u00e0 faire\n\u00e9voluer le mod\u00e8le \u00e9conomique du logement social en France en ouvrant le secteur\n\u00e0 des investisseurs priv\u00e9s.<\/em><\/p>\n\n\n\n<p><em>Le Mouvement Hlm n\u2019est pas dupe, et\nd\u00e9nonce la m\u00e9canique mise en place depuis 2017 :<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><em>Baisse des APL pour les locataires du parc social et mise en place de la R\u00e9duction de Loyer de Solidarit\u00e9, support\u00e9e par les organismes Hlm : pour rappel, le total des \u00e9conomies r\u00e9alis\u00e9es par l\u2019Etat sur le financement du logement social s\u2019\u00e9l\u00e8ve \u00e0 plus de 7 milliards d\u2019euros entre 2017 et 2020 ;<\/em><\/li><li><em>N\u00e9cessit\u00e9 pour les organismes Hlm, pour satisfaire les besoins d\u2019investissement, d\u2019accro\u00eetre leur endettement ;<\/em><\/li><li><em>\u2026 Et aujourd\u2019hui, un rapport administratif \u00ab constate \u00bb la n\u00e9cessit\u00e9 d\u2019ouvrir le financement du logement social \u00e0 des acteurs financiers priv\u00e9s.<\/em><\/li><\/ul>\n\n\n\n<p><em>Sans jamais consid\u00e9rer la situation des\nfamilles aux revenus modestes log\u00e9es en Hlm, ni les deux millions de m\u00e9nages en\nattente d\u2019un logement social, le rapport indique ainsi explicitement que \u00ab\nl\u2019int\u00e9r\u00eat des investisseurs priv\u00e9s pour le logement social est tangible, malgr\u00e9\nun syst\u00e8me laissant peu circuler le capital et soumis \u00e0 un principe de\nlucrativit\u00e9 limit\u00e9e (plafond de dividende, \u00e9valuation des bilans des bailleurs\n\u00e0 la valeur historique du parc et non \u00e0 la valeur de march\u00e9, mises en r\u00e9serve\nobligatoire des plus-values de cessions). \u00bb<\/em><\/p>\n\n\n\n<p><em>Pour rappel, le Mouvement Hlm n&rsquo;a pas\nattendu pour ajuster son mod\u00e8le de financement et travaille avec ses\npartenaires de long terme dans ce domaine, mais il exclut toute solution qui\nfaciliterait la financiarisation de son mod\u00e8le.<\/em><\/p>\n\n\n\n<p><em>Le Mouvement Hlm attend du Gouvernement\nqu\u2019il s\u2019oppose sans ambigu\u00eft\u00e9 \u00e0 toute forme de financiarisation du logement\nsocial au profit d\u2019int\u00e9r\u00eats priv\u00e9s et au d\u00e9triment de sa mission sociale.<\/em><\/p>\n\n\n\n<p><em>Pour Jean-Louis Dumont, pr\u00e9sident de l\u2019Union sociale pour l\u2019habitat<\/em>,\u00a0<em>\u00ab il est devenu dans les habitudes de Bercy de maltraiter le logement social. Avec ce rapport, les masques tombent. Et je pose une question : quels int\u00e9r\u00eats sert ce rapport ? Celui des int\u00e9r\u00eats financiers qui con\u00e7oivent l\u2019immobilier social comme une opportunit\u00e9 par temps de taux bas, ou ceux des habitantes et des habitants qui vivent dans un logement social ou attendent un logement social ? Le choix de la privatisation du logement social, d\u2019autres pays l\u2019ont fait et cela a eu des effets d\u00e9sastreux. Je ne souhaite pas \u00e0 la France, pour sa coh\u00e9sion, ses territoires, son \u00e9conomie, de vivre la m\u00eame exp\u00e9rience. Le logement social est au service des personnes et des familles qui ont des revenus modestes, \u00e7a n\u2019est pas qu\u2019une affaire de tableur Excel. \u00bb<\/em><\/p>\n\n\n\n<p>Lire <a rel=\"noreferrer noopener\" aria-label=\"ici (s\u2019ouvre dans un nouvel onglet)\" href=\"https:\/\/www.union-habitat.org\/communiques-presse\/financement-du-logement-social-l-union-sociale-pour-l-habitat-appelle-le\" target=\"_blank\">ici<\/a> le communiqu\u00e9 de presse de l&rsquo;USH,<\/p>\n\n\n\n<p>&#8230;et <a rel=\"noreferrer noopener\" aria-label=\"l\u00e0 (s\u2019ouvre dans un nouvel onglet)\" href=\"http:\/\/www.igf.finances.gouv.fr\/files\/live\/sites\/igf\/files\/contributed\/IGF%20internet\/2.RapportsPublics\/2019\/2019-M-012-03_Logement%20social_version-publiable.pdf\" target=\"_blank\">l\u00e0<\/a> le rapport de l\u2019IGF.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Datant de juillet 2019, mais publi\u00e9 seulement en novembre, un rapport intitul\u00e9 \u00ab&nbsp;La diversification des sources de financement du secteur du logement locatif social&nbsp;\u00bb a \u00e9t\u00e9 r\u00e9alis\u00e9 par l\u2019inspection G\u00e9n\u00e9rale des finances (IGF) et le Conseil G\u00e9n\u00e9ral de l\u2019environnement et du d\u00e9veloppement durable (CGEDD). Il s\u2019interroge notamment sur la mobilisation des capitaux priv\u00e9s pour financer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[138,281,66,33],"class_list":["post-16579","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-finances","tag-habitat","tag-logement","tag-social"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/16579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=16579"}],"version-history":[{"count":1,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/16579\/revisions"}],"predecessor-version":[{"id":16580,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/16579\/revisions\/16580"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=16579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=16579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=16579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}