{"id":16581,"date":"2019-12-06T14:28:49","date_gmt":"2019-12-06T13:28:49","guid":{"rendered":"https:\/\/www.ades-grenoble.org\/wordpress\/?p=16581"},"modified":"2019-12-06T15:40:45","modified_gmt":"2019-12-06T14:40:45","slug":"territoires-zero-chomeur-trois-rapports-devaluation","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2019\/12\/06\/territoires-zero-chomeur-trois-rapports-devaluation\/","title":{"rendered":"Territoires z\u00e9ro ch\u00f4meur : trois rapports d&rsquo;\u00e9valuation"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"162\" height=\"232\" src=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2019\/12\/TZCLD.jpg\" alt=\"\" class=\"wp-image-16582\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2019\/12\/TZCLD.jpg 162w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2019\/12\/TZCLD-105x150.jpg 105w\" sizes=\"auto, (max-width: 162px) 100vw, 162px\" \/><\/figure><\/div>\n\n\n\n<p>Actuellement\nmen\u00e9e dans dix territoires en vertu d&rsquo;une loi d&rsquo;exp\u00e9rimentation d\u00e9finie pour la\np\u00e9riode 2016-2021, l&rsquo;exp\u00e9rimentation territoriale visant \u00e0 r\u00e9sorber le ch\u00f4mage\nde longue dur\u00e9e fait l&rsquo;objet de nombreuses d\u00e9marches d&rsquo;\u00e9valuation, avant d\u2019en\n\u00e9tudier la suite.<\/p>\n\n\n\n<p>Le 25\nnovembre, sur le site du minist\u00e8re du travail sont \u00e9dit\u00e9s 3 rapports \u00e9valuant\nl\u2019exp\u00e9rimentation \u00ab\u00a0Territoires z\u00e9ro ch\u00f4meurs de longue dur\u00e9e\u00a0\u00bb. Un\nrapport du comit\u00e9 scientifique, un deuxi\u00e8me d\u2019analyse des deux acteurs du\nprojet (le Pr\u00e9sident de Territoires z\u00e9ro ch\u00f4meur de longue dur\u00e9e et le Pr\u00e9sident\ndu Fonds d\u2019exp\u00e9rimentation contre le ch\u00f4mage de longue dur\u00e9e) et enfin le\ntroisi\u00e8me intitul\u00e9 \u00ab&nbsp;<em>L\u2019\u00e9valuation \u00e9conomique de l\u2019exp\u00e9rimentation\nvisant \u00e0 r\u00e9sorber le ch\u00f4mage de longue dur\u00e9e (ETCLD)<\/em>&nbsp;\u00bb par\nl\u2019Inspection g\u00e9n\u00e9rale des finances et celle des affaires sociales.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Le\npremier et le 3<sup>\u00e8me<\/sup> rapport conditionnent l\u2019\u00e9largissement de\nl\u2019exp\u00e9rimentation \u00e0 de nouveaux territoires \u00e0 certaines \u00e9volutions, dont une\nclarification du public cible. Le deuxi\u00e8me du fonds d&rsquo;exp\u00e9rimentation et de l&rsquo;association\nTZCLD (Territoires z\u00e9ro ch\u00f4meurs de longue dur\u00e9e) d\u00e9fendent les principes\nfondateurs du projet, l&rsquo;objectif de mat\u00e9rialiser une forme de \u00ab\u00a0droit \u00e0\nl&#8217;emploi\u00a0\u00bb et l&rsquo;apport global de la d\u00e9marche pour les territoires impliqu\u00e9s.<\/p>\n\n\n\n<p><a rel=\"noreferrer noopener\" aria-label=\"Les trois rapports d'\u00e9valuation  (s\u2019ouvre dans un nouvel onglet)\" href=\"https:\/\/travail-emploi.gouv.fr\/actualites\/l-actualite-du-ministere\/article\/rapports-25-novembre-2019 \" target=\"_blank\">Les trois rapports d&rsquo;\u00e9valuation <\/a>sont sur le site de la Dares. <\/p>\n\n\n\n<p>Le site de l\u2019association TZCLD est <a href=\"https:\/\/www.tzcld.fr\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"ici (s\u2019ouvre dans un nouvel onglet)\">ici<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Actuellement men\u00e9e dans dix territoires en vertu d&rsquo;une loi d&rsquo;exp\u00e9rimentation d\u00e9finie pour la p\u00e9riode 2016-2021, l&rsquo;exp\u00e9rimentation territoriale visant \u00e0 r\u00e9sorber le ch\u00f4mage de longue dur\u00e9e fait l&rsquo;objet de nombreuses d\u00e9marches d&rsquo;\u00e9valuation, avant d\u2019en \u00e9tudier la suite. Le 25 novembre, sur le site du minist\u00e8re du travail sont \u00e9dit\u00e9s 3 rapports \u00e9valuant l\u2019exp\u00e9rimentation \u00ab\u00a0Territoires z\u00e9ro ch\u00f4meurs [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[104,197,33],"class_list":["post-16581","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-economie","tag-emploi","tag-social"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/16581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=16581"}],"version-history":[{"count":1,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/16581\/revisions"}],"predecessor-version":[{"id":16583,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/16581\/revisions\/16583"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=16581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=16581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=16581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}