{"id":18455,"date":"2021-03-05T14:25:36","date_gmt":"2021-03-05T13:25:36","guid":{"rendered":"https:\/\/www.ades-grenoble.org\/wordpress\/?p=18455"},"modified":"2021-10-05T09:14:34","modified_gmt":"2021-10-05T07:14:34","slug":"diverses-actualites-23","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2021\/03\/05\/diverses-actualites-23\/","title":{"rendered":"Diverses actualit\u00e9s"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"222\" src=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2020\/11\/crieur.jpg\" alt=\"\" class=\"wp-image-18106\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2020\/11\/crieur.jpg 400w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2020\/11\/crieur-150x83.jpg 150w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2020\/11\/crieur-300x167.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p><strong>Diagnostic de performance \u00e9nerg\u00e9tique : mise en consultation publique des textes d&rsquo;application. <\/strong>Le nouveau diagnostic de performance \u00e9nerg\u00e9tique (DPE) entrera en vigueur le 1er juillet 2021. <a href=\"http:\/\/www.consultations-publiques.developpement-durable.gouv.fr\/consultation-sur-les-projets-d-arretes-relatifs-au-a2324.html\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Le gouvernement met en consultation jusqu'au 15 mars trois projets d'arr\u00eat\u00e9s concernant les logements. (s\u2019ouvre dans un nouvel onglet)\">Le gouvernement met en consultation jusqu&rsquo;au 15 mars trois projets d&rsquo;arr\u00eat\u00e9s concernant les logements.<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><strong>Le Conseil national d&rsquo;\u00e9valuation des normes a rendu<a rel=\"noreferrer noopener\" aria-label=\" un rapport (s\u2019ouvre dans un nouvel onglet)\" href=\"http:\/\/www.cnen.dgcl.interieur.gouv.fr\/inlinedocs\/a9ad3c7f5b6bd747cea2d43dcbbe1fd0\/rapport-du-cnen-relatif-a-l-intelligibilite-et-a-la-simplification-au-service-de-la-transformation-de-l-action-publique-fevrier-2021.pdf\" target=\"_blank\"> <\/a><a href=\"http:\/\/www.cnen.dgcl.interieur.gouv.fr\/inlinedocs\/c72f4f67430652f4ed44b8e6bd769df5\/rapport-cnen-relatif-a-l-intelligibilite-et-a-la-simplication-des-normes.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">un<\/a><a rel=\"noreferrer noopener\" aria-label=\" un rapport (s\u2019ouvre dans un nouvel onglet)\" href=\"http:\/\/www.cnen.dgcl.interieur.gouv.fr\/inlinedocs\/a9ad3c7f5b6bd747cea2d43dcbbe1fd0\/rapport-du-cnen-relatif-a-l-intelligibilite-et-a-la-simplification-au-service-de-la-transformation-de-l-action-publique-fevrier-2021.pdf\" target=\"_blank\"> rapport<\/a> intitul\u00e9\u00a0<\/strong>: <em>\u00ab\u00a0Rapport relatif \u00e0 l\u2019intelligibilit\u00e9 et \u00e0 la simplification des normes applicables aux collectivit\u00e9s territoriales au service de la transformation de l\u2019action publique\u00a0\u00bb.<\/em> Tout un programme\u00a0! Le principe de libre administration des collectivit\u00e9s est renforc\u00e9, l\u2019exercice des comp\u00e9tences locales assoupli, un pouvoir r\u00e8glementaire augment\u00e9\u2026<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><strong>Evaluation environnementale : <\/strong><a rel=\"noreferrer noopener\" aria-label=\"un nouveau d\u00e9cret en consultation jusqu\u2019au 18 mars (s\u2019ouvre dans un nouvel onglet)\" href=\"http:\/\/www.consultations-publiques.developpement-durable.gouv.fr\/spip.php?page=article&amp;id_article=2325\" target=\"_blank\">un nouveau d\u00e9cret en consultation jusqu\u2019au 18 mars<\/a> pour essayer de d\u00e9samorcer les risques de contentieux europ\u00e9en.Mais ce d\u00e9cret ne r\u00e9pond qu\u2019\u00e0 la mise en demeure de mars 2019 et pas de la derni\u00e8re en f\u00e9vrier 2020. <\/p>\n\n\n\n<!--more-->\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><strong><a rel=\"noreferrer noopener\" aria-label=\"Suivi mensuel des prestations de solidarit\u00e9 pendant la crise sanitaire. (s\u2019ouvre dans un nouvel onglet)\" href=\"https:\/\/drees.solidarites-sante.gouv.fr\/communique-de-presse\/suivi-mensuel-des-prestations-de-solidarite-pendant-la-crise-sanitaire-0\" target=\"_blank\">Suivi mensuel des prestations de solidarit\u00e9 pendant la crise sanitaire<\/a><\/strong><a rel=\"noreferrer noopener\" aria-label=\"Suivi mensuel des prestations de solidarit\u00e9 pendant la crise sanitaire. (s\u2019ouvre dans un nouvel onglet)\" href=\"https:\/\/drees.solidarites-sante.gouv.fr\/communique-de-presse\/suivi-mensuel-des-prestations-de-solidarite-pendant-la-crise-sanitaire-0\" target=\"_blank\">.<\/a> Par la direction de la recherche, des \u00e9tudes, de l&rsquo;\u00e9valuation et des statistiques (Drees) des minist\u00e8res sociaux.<strong> <\/strong>Par exemple, en 2020, le nombre de b\u00e9n\u00e9ficiaires du RSA a progress\u00e9 de 7,5%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diagnostic de performance \u00e9nerg\u00e9tique : mise en consultation publique des textes d&rsquo;application. Le nouveau diagnostic de performance \u00e9nerg\u00e9tique (DPE) entrera en vigueur le 1er juillet 2021. Le gouvernement met en consultation jusqu&rsquo;au 15 mars trois projets d&rsquo;arr\u00eat\u00e9s concernant les logements. Le Conseil national d&rsquo;\u00e9valuation des normes a rendu un rapport intitul\u00e9\u00a0: \u00ab\u00a0Rapport relatif \u00e0 l\u2019intelligibilit\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[226,242,235,175],"class_list":["post-18455","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-collectivites","tag-developpement-durable","tag-energie","tag-environnement"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/18455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=18455"}],"version-history":[{"count":2,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/18455\/revisions"}],"predecessor-version":[{"id":19328,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/18455\/revisions\/19328"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=18455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=18455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=18455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}