{"id":18606,"date":"2021-04-09T14:50:58","date_gmt":"2021-04-09T12:50:58","guid":{"rendered":"https:\/\/www.ades-grenoble.org\/wordpress\/?p=18606"},"modified":"2021-04-09T15:23:42","modified_gmt":"2021-04-09T13:23:42","slug":"evaluation-de-la-strategie-nationale-de-prevention-et-de-lutte-contre-la-pauvrete","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2021\/04\/09\/evaluation-de-la-strategie-nationale-de-prevention-et-de-lutte-contre-la-pauvrete\/","title":{"rendered":"\u00c9valuation de la strat\u00e9gie nationale de pr\u00e9vention et de lutte contre la pauvret\u00e9"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"443\" height=\"128\" src=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2020\/05\/FranceStrategie.jpg\" alt=\"\" class=\"wp-image-17259\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2020\/05\/FranceStrategie.jpg 443w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2020\/05\/FranceStrategie-150x43.jpg 150w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2020\/05\/FranceStrategie-300x87.jpg 300w\" sizes=\"auto, (max-width: 443px) 100vw, 443px\" \/><\/figure><\/div>\n\n\n\n<p>Le Comit\u00e9 d\u2019\u00e9valuation de la strat\u00e9gie nationale de pr\u00e9vention et de lutte contre la pauvret\u00e9 a rendu <a href=\"https:\/\/www.strategie.gouv.fr\/publications\/evaluation-de-strategie-nationale-de-prevention-de-lutte-contre-pauvrete-rapport-2021\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"son rapport 2021 (s\u2019ouvre dans un nouvel onglet)\">son rapport 2021<\/a>. Cette strat\u00e9gie, lanc\u00e9e par Macron en septembre 2018, peine \u00e0 donner des r\u00e9sultats. Encore beaucoup de communication et peu d\u2019actions r\u00e9elles. Parmi les 35 mesures de pr\u00e9vention et de lutte contre la pauvret\u00e9 seules quatre ont \u00e9t\u00e9 int\u00e9gralement mises en \u0153uvre. Il s\u2019agit de la revalorisation de la prime d\u2019activit\u00e9, de la mise en \u0153uvre et du renouvellement de la compl\u00e9mentaire sant\u00e9 solidaire pour les allocataires du RSA, et du d\u00e9ploiement de 400 points conseils budget. <\/p>\n\n\n\n<p><em>\u00ab&nbsp;Evaluation de la\ngouvernance et du volet territorial de la strat\u00e9gie.<\/em><\/p>\n\n\n\n<p><em>&nbsp;L\u2019organisation pr\u00e9vue pour piloter la\nStrat\u00e9gie a bien \u00e9t\u00e9 mise en place, malgr\u00e9 certains retards. Les moyens\nfinanciers annonc\u00e9s ont \u00e9t\u00e9 confirm\u00e9s, rendant ainsi cr\u00e9dible l\u2019engagement de\nl\u2019\u00c9tat, notamment vis-\u00e0-vis des collectivit\u00e9s. Toutefois, le comit\u00e9 souligne un\npoint d\u2019alerte important : le soutien politique de la Strat\u00e9gie reste\ninsuffisant pour donner \u00e0 la d\u00e9l\u00e9gation qui en a la charge les moyens d\u2019une\ncoordination interminist\u00e9rielle et d\u2019un pilotage propre \u00e0 garantir un niveau de\nmise en \u0153uvre \u00e0 la hauteur des ambitions initiales.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<!--more-->\n\n\n\n<p>A noter que l\u2019activit\u00e9 du\npremier d\u00e9l\u00e9gu\u00e9 interminist\u00e9riel, O. Noblecourt n\u2019a pas marqu\u00e9 les esprits. Il\nn\u2019est cit\u00e9 qu\u2019une seule fois dans le rapport 2021, juste pour signaler qu\u2019il a\n\u00e9t\u00e9 remplac\u00e9 en mars 2020. Et dans le rapport pr\u00e9c\u00e9dent de 2020, il n\u2019est m\u00eame\npas cit\u00e9.<\/p>\n\n\n\n<p>Dans les recommandations du\ncomit\u00e9 d\u2019\u00e9valuation, il est propos\u00e9 d\u2019exp\u00e9rimenter, sans d\u00e9lai, un\nrevenu de base pour les 18-24 ans les plus d\u00e9munis. Car rien n\u2019est fait pour ce\nsegment fragile de la population.<\/p>\n\n\n\n<p><em>\u00ab&nbsp;Recommandation 10 <\/em><\/p>\n\n\n\n<p><em>La crise sanitaire a\nsoulign\u00e9 les limites, pour les \u00e9tudiants, les jeunes en recherche d\u2019emploi, et\nles jeunes en emploi les plus d\u00e9munis, du syst\u00e8me actuel reposant sur l\u2019aide\nparentale et sur des revenus d\u2019appoint tir\u00e9s de petits boulots. Pour le comit\u00e9\nd\u2019\u00e9valuation, les \u00e9l\u00e9ments d\u2019information d\u00e9j\u00e0 disponibles sont suffisants pour\nrecommander d\u2019exp\u00e9rimenter sans d\u00e9lai la mise en place d\u2019une prestation\nmon\u00e9taire pour ces jeunes. Il recommande d\u2019exp\u00e9rimenter sans d\u00e9lai la mise en\nplace d\u2019une prestation mon\u00e9taire pour les jeunes en \u00e9tude, en emploi peu r\u00e9mun\u00e9r\u00e9,\nou en recherche d\u2019emploi de 18 \u00e0 24 ans les plus d\u00e9munis, afin d\u2019observer les e\u00adffets\nr\u00e9els d\u2019une telle politique et d\u2019\u00e9clairer la d\u00e9cision publique sur son\n\u00e9ventuelle pertinence. Ce revenu de base serait sous conditions de ressources\net en prenant en compte la solidarit\u00e9 familiale sous r\u00e9serve que le jeune\npuisse en b\u00e9n\u00e9ficier, et de montant similaire et soumis aux m\u00eames conditions\nquel que soit le statut des jeunes vis-\u00e0-vis des \u00e9tudes ou de l&#8217;emploi. Il est\nimportant d\u2019off\u00adrir un accompagnement de qualit\u00e9 aux jeunes le recevant. Ce\nrevenu de base devrait \u00eatre une prestation nationale. <\/em><\/p>\n\n\n\n<p><em>L\u2019exp\u00e9rimentation se\nfera au niveau national si une d\u00e9cision nationale est rapidement prise. En\nl\u2019absence d\u2019une telle d\u00e9cision, elle se fera au niveau d\u00e9partemental dans des\nd\u00e9partements volontaires. Au moment de l\u2019introduction du revenu universel\nd\u2019activit\u00e9 (RUA) ou d\u2019une prestation de ce type, il faudrait, si\nl\u2019exp\u00e9rimentation du revenu de base est concluante, veiller \u00e0 la coh\u00e9rence\nentre les deux dispositifs&nbsp;\u00bb.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Comit\u00e9 d\u2019\u00e9valuation de la strat\u00e9gie nationale de pr\u00e9vention et de lutte contre la pauvret\u00e9 a rendu son rapport 2021. Cette strat\u00e9gie, lanc\u00e9e par Macron en septembre 2018, peine \u00e0 donner des r\u00e9sultats. Encore beaucoup de communication et peu d\u2019actions r\u00e9elles. Parmi les 35 mesures de pr\u00e9vention et de lutte contre la pauvret\u00e9 seules quatre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[298,181,256],"class_list":["post-18606","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-france","tag-precarite","tag-prevention"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/18606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=18606"}],"version-history":[{"count":1,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/18606\/revisions"}],"predecessor-version":[{"id":18607,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/18606\/revisions\/18607"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=18606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=18606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=18606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}