{"id":20643,"date":"2022-08-16T09:53:46","date_gmt":"2022-08-16T07:53:46","guid":{"rendered":"https:\/\/www.ades-grenoble.org\/wordpress\/?p=20643"},"modified":"2022-08-16T10:07:59","modified_gmt":"2022-08-16T08:07:59","slug":"encore-une-polemique-ridicule-sur-les-piscines-grenobloises","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2022\/08\/16\/encore-une-polemique-ridicule-sur-les-piscines-grenobloises\/","title":{"rendered":"Encore une pol\u00e9mique ridicule sur les piscines grenobloises"},"content":{"rendered":"<div class=\"wp-block-image is-style-default\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"530\" height=\"690\" src=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2022\/05\/picto-piscines.jpg\" alt=\"\" class=\"wp-image-20419\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2022\/05\/picto-piscines.jpg 530w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2022\/05\/picto-piscines-230x300.jpg 230w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2022\/05\/picto-piscines-115x150.jpg 115w\" sizes=\"auto, (max-width: 530px) 100vw, 530px\" \/><\/figure>\n<\/div>\n\n\n<p>Depuis le 25 mai 2022, le r\u00e8glement int\u00e9rieur des piscines municipales de Grenoble pr\u00e9cise quelles sont les tenues de bain autoris\u00e9es et interdites. Le 28 juillet deux femmes ont tent\u00e9 de porter des tenues non autoris\u00e9es n\u2019\u00e9tant pas ajust\u00e9es pr\u00e8s du corps. Par contre 5 autres usag\u00e8res de la piscine ont port\u00e9 des tenues int\u00e9grales ajust\u00e9es pr\u00e8s du corps et ont donc pu se baigner.<\/p>\n\n\n\n<p>L\u2019opposition a imm\u00e9diatement relanc\u00e9 la pol\u00e9mique sur le burkini, l\u2019ancien maire corrompu, A. Carignon a consid\u00e9r\u00e9 que le maire de Grenoble n\u2019avait pas appliqu\u00e9 la d\u00e9cision de justice et en a appel\u00e9 au pr\u00e9fet, allant jusqu\u2019\u00e0 demander que le maire soit suspendu de sa fonction. Evidemment cette agitation purement politicienne et totalement infond\u00e9e a fait plouf. Mais pour continuer \u00e0 s\u2019agiter, le groupe d\u2019opposition pr\u00e9sid\u00e9 par le corrompu a d\u00e9pos\u00e9 le 12 ao\u00fbt une plainte aupr\u00e8s du procureur de la R\u00e9publique de Grenoble. Si notre justice en avait les moyens elle attaquerait le corrompu pour d\u00e9nonciation calomnieuse puisque la ville a respect\u00e9 l\u2019article 10 du r\u00e8glement valid\u00e9 par le Conseil d\u2019Etat.<\/p>\n\n\n\n<p>La Ville de Grenoble a donn\u00e9 des pr\u00e9cisions sur le d\u00e9roulement des faits par <a href=\"https:\/\/www.grenoble.fr\/uploads\/Externe\/54\/1487_739_CP-Reglement-des-piscines-municipales-precisions-de-la-Ville-de-Grenoble.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">un communiqu\u00e9 du 29 juillet<\/a>\u00a0:<\/p>\n\n\n\n<!--more-->\n\n\n\n<p><em>\u00ab&nbsp;La Ville de Grenoble indique que toutes les baigneuses et tous les baigneurs pr\u00e9sent-es jeudi matin 28 Juillet dans la piscine Jean Bron portaient bien des v\u00eatements de bain conformes \u00e0 l\u2019article 10 du r\u00e8glement int\u00e9rieur des piscines municipales, lui-m\u00eame modifi\u00e9 et mis en conformit\u00e9 suite \u00e0 l\u2019ordonnance du Tribunal Administratif de Grenoble du 25 mai 2022 confirm\u00e9e par le Conseil d\u2019\u00c9tat du 21 juin dernier.<\/em><\/p>\n\n\n\n<p><em>La Ville rappelle \u00e0 toutes et tous que cette jurisprudence a apport\u00e9 de r\u00e9elles avanc\u00e9es puisqu\u2019elle permet, au-del\u00e0 du point suspendu par le tribunal administratif, l\u2019\u00e9galit\u00e9 pour les femmes et les hommes par l\u2019autorisation du monokini (ou Topless) pour les femmes, prot\u00e8ge la sant\u00e9 et am\u00e9liore l\u2019universalit\u00e9 d\u2019acc\u00e8s du service public \u00e0 toutes et tous en autorisant de porter des tenues de bain couvrantes \u00ab ajust\u00e9es pr\u00e8s du corps \u00bb.<\/em><\/p>\n\n\n\n<p><em>Suite \u00e0 plusieurs approximations parues publiquement dans la presse et sur les r\u00e9seaux sociaux jeudi apr\u00e8s-midi, la Ville tient donc \u00e0 apporter plusieurs pr\u00e9cisions sur les faits relat\u00e9s. Tout d\u2019abord, la Ville rappelle que l\u2019ordonnance n\u00b0 2203163 du tribunal administratif de Grenoble, en date du 25 mai 2022 a \u00e9t\u00e9 imm\u00e9diatement mise en \u0153uvre et l\u2019article 10 du r\u00e8glement a \u00e9t\u00e9 modifi\u00e9 s\u2019agissant du point suspendu concernant les tenues non pr\u00e8s du corps descendant le long des cuisses. L\u2019ordonnance n\u00b0464648 du Conseil d\u2019\u00c9tat le 21 Juin a ensuite confirm\u00e9 l\u2019ordonnance du Tribunal administratif.<\/em><\/p>\n\n\n\n<p><em>Jeudi matin, un groupe de sept personnes s\u2019est rendu \u00e0 la piscine Jean Bron. \u00c0 la sortie des vestiaires, le personnel de la piscine a proc\u00e9d\u00e9 de mani\u00e8re classique \u00e0 la v\u00e9rification des tenues de bain. Plusieurs personnes pr\u00e9sentaient un v\u00eatement conforme, c\u2019est-\u00e0-dire faites d\u2019un tissu sp\u00e9cifiquement con\u00e7u pour la baignade, ajust\u00e9 pr\u00e8s du corps, de diff\u00e9rentes longueurs, du monokini (ou top less) au maillot de bain couvrant. Elles ont donc \u00e9t\u00e9 autoris\u00e9es \u00e0 rentrer dans le bassin par les agent-es du service des sports. Concernant deux usag\u00e8res, les tenues ont \u00e9t\u00e9 jug\u00e9es non conformes par les agent-es, qui ont contact\u00e9 la mairie centrale sur ce cas pr\u00e9cis, avant de confirmer aux personnes concern\u00e9es que les tenues \u00e9taient non conformes au r\u00e8glement int\u00e9rieur amend\u00e9 depuis par la jurisprudence du Conseil d\u2019\u00c9tat. Ces personnes ne sont donc pas entr\u00e9es dans la zone de baignade et ont quitt\u00e9 l\u2019\u00e9tablissement. Les autres personnes pr\u00e9sentant un maillot de bain conforme au r\u00e8glement (article 10) ont donc pu acc\u00e9der aux bassins comme tous-tes les autres usager-es\u2026\u00a0\u00bb<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis le 25 mai 2022, le r\u00e8glement int\u00e9rieur des piscines municipales de Grenoble pr\u00e9cise quelles sont les tenues de bain autoris\u00e9es et interdites. Le 28 juillet deux femmes ont tent\u00e9 de porter des tenues non autoris\u00e9es n\u2019\u00e9tant pas ajust\u00e9es pr\u00e8s du corps. Par contre 5 autres usag\u00e8res de la piscine ont port\u00e9 des tenues int\u00e9grales [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[67,215,52],"class_list":["post-20643","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-conseil-municipal","tag-grenoble","tag-justice-administrative"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/20643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=20643"}],"version-history":[{"count":1,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/20643\/revisions"}],"predecessor-version":[{"id":20644,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/20643\/revisions\/20644"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=20643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=20643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=20643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}