{"id":22767,"date":"2024-02-09T16:55:32","date_gmt":"2024-02-09T15:55:32","guid":{"rendered":"https:\/\/www.ades-grenoble.org\/wordpress\/?p=22767"},"modified":"2024-02-09T18:19:29","modified_gmt":"2024-02-09T17:19:29","slug":"annulation-des-elections-des-conseils-centraux-de-luniversite-grenoble-alpes","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2024\/02\/09\/annulation-des-elections-des-conseils-centraux-de-luniversite-grenoble-alpes\/","title":{"rendered":"Annulation des \u00e9lections des conseils centraux de l\u2019Universit\u00e9 Grenoble Alpes"},"content":{"rendered":"<div class=\"wp-block-image is-style-default\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"224\" height=\"145\" src=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/04\/UGA.jpg\" alt=\"\" class=\"wp-image-12900\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/04\/UGA.jpg 224w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2017\/04\/UGA-150x97.jpg 150w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><\/figure>\n<\/div>\n\n\n<p>Ce qui se passe \u00e0 l\u2019UGA n\u2019est pas toujours respectueux du droit et ce qui s\u2019est pass\u00e9 lors des \u00e9lections des conseils de l\u2019universit\u00e9, montre que des pratiques non d\u00e9mocratiques ont la vie dure, jusqu\u2019\u00e0 tout faire pour emporter des \u00e9lections.\u00a0 A la demande de personnels de l\u2019UGA soutenus par le SNESup, <a href=\"https:\/\/grenoble.tribunal-administratif.fr\/Media\/mediatheque-ta-grenoble\/documents\/2024\/fevrier\/2308224\" data-type=\"link\" data-id=\"https:\/\/grenoble.tribunal-administratif.fr\/Media\/mediatheque-ta-grenoble\/documents\/2024\/fevrier\/2308224\">le tribunal administratif a annul\u00e9 le 8 f\u00e9vrier les \u00e9lections<\/a>. Le Pr\u00e9sident sortant est lourdement mis en cause dans ce jugement.<\/p>\n\n\n\n<p>Le tribunal annule l\u2019ensemble des op\u00e9rations \u00e9lectorales des 28 et 30 novembre 2023 visant au renouvellement des repr\u00e9sentants des personnels dans les conseils centraux universitaires du fait d\u2019une intervention du Pr\u00e9sident dans les op\u00e9rations \u00e9lectorales ayant affect\u00e9 la sinc\u00e9rit\u00e9 du scrutin alors que celui-ci \u00e9tait charg\u00e9 de veiller au respect du principe d\u2019\u00e9galit\u00e9 entre les listes candidates.<\/p>\n\n\n\n<p>L\u2019Universit\u00e9 Grenoble Alpes (UGA) a organis\u00e9 des \u00e9lections en vue du renouvellement des repr\u00e9sentants des personnels dans ses conseils centraux, \u00e0 savoir le conseil d\u2019administration, la commission de la formation et de la vie universitaire et la commission de la recherche. Ces \u00e9lections se sont tenues du 28 au 30 novembre 2023 et les r\u00e9sultats ont \u00e9t\u00e9 proclam\u00e9s le 2 d\u00e9cembre 2023. Huit \u00e9lecteurs et un syndicat ont alors demand\u00e9 l\u2019annulation de ces \u00e9lections, d\u2019abord en formant un recours pr\u00e9alable puis devant le tribunal administratif qui a \u00e9t\u00e9 saisi le 20 d\u00e9cembre 2023.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Or, le pr\u00e9sident de l\u2019universit\u00e9, candidat \u00e0 sa r\u00e9\u00e9lection, a adress\u00e9 un message \u00e9lectronique le 26 novembre 2023, \u00e0 des destinataires masqu\u00e9s les invitant notamment \u00e0 \u00ab&nbsp;se mobiliser pour&nbsp;faire barrage&nbsp;\u00bb \u00e0 une candidature adverse en pr\u00e9cisant les listes susceptibles de soutenir ce candidat. Ce message a \u00e9t\u00e9 largement relay\u00e9 par au moins deux destinataires.<\/p>\n\n\n\n<p>Le tribunal a estim\u00e9 que ce message comportait un contenu tr\u00e8s critique et des accusations personnelles pour orienter le vote&nbsp;; qu\u2019en outre il s\u2019inscrivait hors du cadre officiel de la campagne, selon des proc\u00e9d\u00e9s qui \u00e9taient interdits aux syndicats pr\u00e9sentant des candidats et en excluant tout r\u00e9plique utile des personnes mises en cause compte tenu de sa nature et de sa date de diffusion.<\/p>\n\n\n\n<p>Le tribunal a, en cons\u00e9quence, retenu que le pr\u00e9sident, qui n\u2019\u00e9tait pas candidat \u00e0 ce stade, \u00e9tait charg\u00e9 de veiller au respect du principe d\u2019\u00e9galit\u00e9 entre les listes candidates et ne pouvait faire campagne pour ou contre l\u2019une ou l\u2019autre des listes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce qui se passe \u00e0 l\u2019UGA n\u2019est pas toujours respectueux du droit et ce qui s\u2019est pass\u00e9 lors des \u00e9lections des conseils de l\u2019universit\u00e9, montre que des pratiques non d\u00e9mocratiques ont la vie dure, jusqu\u2019\u00e0 tout faire pour emporter des \u00e9lections.\u00a0 A la demande de personnels de l\u2019UGA soutenus par le SNESup, le tribunal administratif [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[52,267],"class_list":["post-22767","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-justice-administrative","tag-universite"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/22767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=22767"}],"version-history":[{"count":1,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/22767\/revisions"}],"predecessor-version":[{"id":22768,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/22767\/revisions\/22768"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=22767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=22767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=22767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}