{"id":23171,"date":"2024-05-03T11:56:10","date_gmt":"2024-05-03T09:56:10","guid":{"rendered":"https:\/\/www.ades-grenoble.org\/wordpress\/?p=23171"},"modified":"2024-05-03T11:56:10","modified_gmt":"2024-05-03T09:56:10","slug":"jo-dhiver-2030-dans-les-alpes-les-incertitudes-restent","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2024\/05\/03\/jo-dhiver-2030-dans-les-alpes-les-incertitudes-restent\/","title":{"rendered":"JO d\u2019hiver 2030 dans les Alpes\u2026 les incertitudes restent"},"content":{"rendered":"<div class=\"wp-block-image is-style-default\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"294\" src=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2016\/11\/canon-neige.jpg\" alt=\"\" class=\"wp-image-12252\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2016\/11\/canon-neige.jpg 350w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2016\/11\/canon-neige-150x126.jpg 150w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2016\/11\/canon-neige-300x252.jpg 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/figure>\n<\/div>\n\n\n<p>Les deux pr\u00e9sidents d\u2019Auvergne Rh\u00f4ne Alpes (Wauquiez) et de Provence Alpes C\u00f4te d\u2019Azur (Muselier) esp\u00e8rent avoir d\u00e9croch\u00e9 les JO d\u2019hiver de 2030&nbsp;; \u00e9tant les seuls candidats, ils n\u2019avaient pas besoin d\u2019avoir un dossier de candidature au top. Du coup il y a de nombreuses incertitudes dans ce dossier.<\/p>\n\n\n\n<p>Le 28 avril 2024, le quotidien <a href=\"https:\/\/www.liberation.fr\/sports\/jo-2030-dans-les-alpes-le-cio-est-reparti-les-incertitudes-restent-20240428_PSZKXTTRIVDF5LNRVKFZLZDAKY\/\" data-type=\"link\" data-id=\"https:\/\/www.liberation.fr\/sports\/jo-2030-dans-les-alpes-le-cio-est-reparti-les-incertitudes-restent-20240428_PSZKXTTRIVDF5LNRVKFZLZDAKY\/\"><em>Lib\u00e9ration<\/em> a fait un point d\u00e9taill\u00e9 sur l\u2019\u00e9tat du dossier<\/a> apr\u00e8s le passage dans les Alpes du Comit\u00e9 international olympique. Pour le comit\u00e9 tout doit \u00eatre boucl\u00e9 d\u2019ici les Jeux de Paris.<\/p>\n\n\n\n<p>Voici des extraits de l\u2019article de <em>Lib\u00e9ration<\/em>&nbsp;:<\/p>\n\n\n\n<p><strong><em>\u00ab&nbsp;Budget global revu \u00e0 la hausse<\/em><\/strong><\/p>\n\n\n\n<p><em>L\u2019addition fr\u00f4le d\u00e9sormais les 2 milliards d\u2019euros pour le seul comit\u00e9 d\u2019organisation m\u00eame si le budget de fonctionnement est th\u00e9oriquement abond\u00e9 par le CIO et les recettes de l\u2019\u00e9v\u00e8nement. \u00abOn ne va pas les d\u00e9passer\u00bb, promet Muselier. \u00abNous souhaitons aussi que ce soit un co\u00fbt ma\u00eetris\u00e9\u00bb, rench\u00e9rit David Lappartient<\/em>.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p><em>Ceci dit, ce montant deux fois moins \u00e9lev\u00e9 que celui des jeux de Paris cet \u00e9t\u00e9 ne prend pas en compte le co\u00fbt des infrastructures qui sont envisag\u00e9es, ce qui co\u00fbterait \u00abde un \u00e0 deux milliards\u00bb suppl\u00e9mentaires selon la tr\u00e8s large fourchette donn\u00e9e par Wauquiez vendredi lors de la conf\u00e9rence de presse de cl\u00f4ture de visite. \u00abOn sera tr\u00e8s nettement en dessous des 4 milliards de Paris, assure-t-il. On a jusqu\u2019\u00e0 l\u2019\u00e9t\u00e9 pour boucler le budget. On va mettre \u00e0 niveau les \u00e9quipements en \u00e9tant sobres. Pas d\u2019\u00e9l\u00e9phant blanc. On ne fait pas n\u2019importe quoi. Pas de folie, pas de grande construction, pas de d\u00e9mesure.\u00bb<\/em><\/p>\n\n\n\n<p><em>Derri\u00e8re les grands discours et cette promesse de sobri\u00e9t\u00e9 \u2013 une figure impos\u00e9e \u00e0 l\u2019heure o\u00f9 les grands projets sont de plus en plus contest\u00e9s par les citoyens \u2013 se dessine pourtant un programme charg\u00e9 de constructions et d\u2019am\u00e9nagements. Pour certains, il n\u2019est pas certain qu\u2019il soit possible de les r\u00e9aliser d\u2019ici 2029. Ils sont projet\u00e9s sur chacun des quatre \u00abp\u00f4les\u00bb pr\u00e9vus pour ces Jeux d\u00e9concentr\u00e9s : en Haute-Savoie (Grand-Bornand et La Clusaz, dans le massif des Aravis), en Savoie (Courchevel, M\u00e9ribel et La Plagne, en vall\u00e9e de la Tarentaise), dans les Hautes-Alpes (Serre-Chevalier et Montgen\u00e8vre, dans le Brian\u00e7onnais) et dans les Alpes-Maritimes (Nice).<\/em><\/p>\n\n\n\n<p><strong><em>Probl\u00e8me de neige dans les Aravis<\/em><\/strong><\/p>\n\n\n\n<p><em>Le village olympique serait abrit\u00e9 dans un futur village vacances de 700 lits que l\u2019op\u00e9rateur priv\u00e9 MMV ambitionne de construire d\u2019ici 2027 au Grand-Bornand, qui accueillera le biathlon. Le montage financier reste inconnu et il faut encore trouver 200 lits. Pour les \u00e9preuves de ski de fond \u00e0 la Clusaz, le domaine nordique des Confins est situ\u00e9 sur une zone naturelle sensible et largement prot\u00e9g\u00e9e et devra \u00eatre s\u00e9rieusement r\u00e9am\u00e9nag\u00e9 pour accueillir 12 500 personnes les jours d\u2019\u00e9preuves ainsi qu\u2019un b\u00e2timent \u00absemi-enterr\u00e9\u00bb pour le centre de presse, le chronom\u00e9trage et les installations du contr\u00f4le antidopage. L\u2019enneigement artificiel et le \u00absnowfarming\u00bb (stockage de neige) seront renforc\u00e9s pour ce site situ\u00e9 \u00e0 1 400 m\u00e8tres d\u2019altitude seulement.<\/em><\/p>\n\n\n\n<p><em>La m\u00eame menace p\u00e8se sur le stade de biathlon du Grand-Bornand, qui se trouve lui \u00e0 1 000 m\u00e8tres \u00e0 peine. En 2022, la station avait d\u00fb acheminer 12 000 m\u00b3 de neige par camion sur le site pour assurer une coupe du monde. L\u2019al\u00e9a climatique ne fera que se renforcer d\u2019ici 2030. Le d\u00e9veloppement de la neige de culture sera donc l\u00e0 encore in\u00e9vitable pour s\u00e9curiser les JO, au sein d\u2019un r\u00e9am\u00e9nagement plus large du site \u00e9valu\u00e9 \u00e0 50 millions d\u2019euros. Autre flou pour les Aravis, ses infrastructures routi\u00e8res limit\u00e9es : Wauquiez promet \u00abl\u2019optimisation de la mobilit\u00e9 douce avec un r\u00e9seau de transport d\u00e9carbon\u00e9\u00bb, dont un tr\u00e8s impr\u00e9cis t\u00e9l\u00e9ph\u00e9rique \u00abascenseur vall\u00e9en\u00bb sur le versant du massif situ\u00e9 du c\u00f4t\u00e9 d\u2019Annecy. L\u2019ouvrage est encore \u00ab \u00e0 l\u2019\u00e9tude \u00bb\u2026<\/em><\/p>\n\n\n\n<p><strong><em>Des \u00ab&nbsp;Jeux pour les Jeux pas pour les gens \u00bb<\/em><\/strong><\/p>\n\n\n\n<p><em>Le dossier\u202freste donc inachev\u00e9. D\u2019ici \u00e0 juin, il va falloir faut non seulement pr\u00e9ciser les infrastructures pr\u00e9vues, les financements, les calendriers, mais m\u00eame certains lieux, dont celui de la c\u00e9r\u00e9monie d\u2019ouverture. Pour l\u2019instant, la seule chose qu\u2019on sait c\u2019est qu\u2019elle combinerait \u00abplusieurs sites\u00bb, selon Laurent Wauquiez. Face \u00e0 cette accumulation d\u2019incertitudes, \u00e0 quelques semaines du bouclage th\u00e9orique du dossier, un collectif de citoyens, d\u2019associations et d\u2019\u00e9lus de Haute-Savoie vient de lancer <\/em><em><a href=\"https:\/\/chng.it\/cLPBvdp5C6\">une p\u00e9tition<\/a><\/em><em> exigeant un d\u00e9bat public urgent dans tous les territoires concern\u00e9s, qui \u00abvont \u00eatre durablement affect\u00e9s par les Jeux\u00bb.<\/em><\/p>\n\n\n\n<p><em>Signataire de la p\u00e9tition, Fabienne Gr\u00e9bert, \u00e9lue r\u00e9gionale \u00e9colo face \u00e0 la majorit\u00e9 Wauquiez, s\u2019indigne : \u00abOn parle donc d\u2019un budget \u00e0 4 milliards d\u2019euros au total, or \u00e0 trois mois de la d\u00e9cision nous n\u2019avons aucune information sur qui finance quoi et aucune vision sur la destin\u00e9e des \u00e9quipements, leurs impacts environnementaux.\u00bb La conseill\u00e8re r\u00e9gionale d\u2019opposition d\u00e9nonce un projet au co\u00fbt \u00e9norme et au budget \u00abfarfelu\u00bb, men\u00e9 sans transparence ni d\u00e9mocratie, \u00abhors programme \u00e9lectoral\u00bb, par \u00abtrois \u00e9lus LR visant leur destin\u00e9e personnelle\u00bb. Elle r\u00e9sume l\u2019inqui\u00e9tude dominante : que l\u2019on fasse \u00abdes Jeux pour Jeux, pas pour les gens\u00bb. Au fond, s\u2019interroge Fabienne Gr\u00e9bert, de quelles garanties les trois hommes disposent-ils r\u00e9ellement au sommet de l\u2019Etat ? Au moins deux d\u2019entre eux \u2013 Muselier et Estrosi \u2013 se disent proches d\u2019Emmanuel Macron, qui n\u2019a pas dit un mot cette semaine pendant toute la visite du CIO.\u00a0\u00bb<\/em> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les deux pr\u00e9sidents d\u2019Auvergne Rh\u00f4ne Alpes (Wauquiez) et de Provence Alpes C\u00f4te d\u2019Azur (Muselier) esp\u00e8rent avoir d\u00e9croch\u00e9 les JO d\u2019hiver de 2030&nbsp;; \u00e9tant les seuls candidats, ils n\u2019avaient pas besoin d\u2019avoir un dossier de candidature au top. Du coup il y a de nombreuses incertitudes dans ce dossier. Le 28 avril 2024, le quotidien Lib\u00e9ration [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[138,20,179,73],"class_list":["post-23171","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-finances","tag-jo","tag-presse","tag-sports"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/23171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=23171"}],"version-history":[{"count":1,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/23171\/revisions"}],"predecessor-version":[{"id":23172,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/23171\/revisions\/23172"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=23171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=23171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=23171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}