{"id":3744,"date":"2011-04-01T19:34:35","date_gmt":"2011-04-01T17:34:35","guid":{"rendered":"http:\/\/www.ades-grenoble.org\/wordpress\/?p=3744"},"modified":"2011-04-01T19:34:35","modified_gmt":"2011-04-01T17:34:35","slug":"le-droit-de-manifester-bafoue-par-la-prefecture","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2011\/04\/01\/le-droit-de-manifester-bafoue-par-la-prefecture\/","title":{"rendered":"Le droit de manifester bafou\u00e9 par la Pr\u00e9fecture"},"content":{"rendered":"<p>Le mercredi 30 mars de nombreuses organisations se proposaient de passer la nuit en face de la Pr\u00e9fecture pour tirer la sonnette d\u2019alarme sur le nombre tr\u00e8s important de personnes qui allaient se retrouver \u00e0 la rue apr\u00e8s la p\u00e9riode hivernale. En effet, le Pr\u00e9fet ferme brutalement les h\u00e9bergements hivernaux qui abritaient environ 550 personnes. Cette manifestation de \u00ab\u00a0la nuit solidaire\u00a0\u00bb, pacifique et non violente a \u00e9t\u00e9 r\u00e9prim\u00e9e de mani\u00e8re totalement disproportionn\u00e9e. Alors que les tentes n&rsquo;\u00e9taient pas mont\u00e9es, les toiles \u00e0 peine  \u00e9tal\u00e9es sur le sol, les gendarmes mobiles ont sans un mot charg\u00e9 \u00e0 coups de matraques les personnes pr\u00e9sentes avec une rare violence, et arr\u00eat\u00e9 un militant.<\/p>\n<p>L\u2019ADES s\u2019\u00e9l\u00e8ve vivement contre ces proc\u00e9d\u00e9s inadmissibles. Voil\u00e0 la seule r\u00e9ponse donn\u00e9e par l&rsquo;Etat \u00e0 la demande des citoyens et des familles en difficult\u00e9s. Le Pr\u00e9fet policier, au lieu de concentrer ses efforts pour am\u00e9liorer la s\u00e9curit\u00e9 et prot\u00e9ger les citoyens, utilise les fonctionnaires de police pour r\u00e9primer des manifestations l\u00e9gitimes et non violentes.<\/p>\n<p><em>Derni\u00e8re nouvelle<\/em>, le dispositif d\u2019h\u00e9bergement hivernal est prolong\u00e9 jusqu\u2019\u00e0 fin avril, mais cela ne r\u00e8gle pas le probl\u00e8me de fond.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le mercredi 30 mars de nombreuses organisations se proposaient de passer la nuit en face de la Pr\u00e9fecture pour tirer la sonnette d\u2019alarme sur le nombre tr\u00e8s important de personnes qui allaient se retrouver \u00e0 la rue apr\u00e8s la p\u00e9riode hivernale. En effet, le Pr\u00e9fet ferme brutalement les h\u00e9bergements hivernaux qui abritaient environ 550 personnes. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[1],"tags":[12,33],"class_list":["post-3744","post","type-post","status-publish","format-standard","hentry","category-actus","tag-mobilisations","tag-social"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/3744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=3744"}],"version-history":[{"count":2,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/3744\/revisions"}],"predecessor-version":[{"id":3746,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/3744\/revisions\/3746"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=3744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=3744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=3744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}