{"id":5206,"date":"2012-02-05T19:21:21","date_gmt":"2012-02-05T17:21:21","guid":{"rendered":"http:\/\/www.ades-grenoble.org\/wordpress\/?p=5206"},"modified":"2012-02-05T19:21:21","modified_gmt":"2012-02-05T17:21:21","slug":"les-finances-de-la-metro","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2012\/02\/05\/les-finances-de-la-metro\/","title":{"rendered":"Les finances de la M\u00e9tro"},"content":{"rendered":"<p>Il faut marquer l\u2019ann\u00e9e 2011 d\u2019une pierre blanche car pour la premi\u00e8re fois depuis sa cr\u00e9ation, la M\u00e9tro voit sa dette tr\u00e8s l\u00e9g\u00e8rement diminuer. Il vaut mieux parler de stabilisation car la diminution de 0,5 M\u20ac du stock sur 350 M\u20ac est symbolique.<\/p>\n<p>C\u2019est une bonne nouvelle, mais acquise gr\u00e2ce aux fortes augmentations de la fiscalit\u00e9 ces derni\u00e8res ann\u00e9es (plus de 25 M\u20ac) et des imp\u00f4ts (taxes d\u2019habitation et fonci\u00e8res et la TEOM) ont rapport\u00e9 nettement plus que pr\u00e9vu en 2011.<\/p>\n<p>En revanche \u00e0 cause des emprunts toxiques, les taux d\u2019int\u00e9r\u00eats en 2012 vont augmenter fortement.<\/p>\n<p>Mais la stabilisation de la dette se confirmera-t-elle ? C\u2019est une des questions qu\u2019a os\u00e9 poser Gilles Kuntz en s\u2019\u00e9tonnant que le projet de budget inscrivait 40 M\u20ac d\u2019emprunts en 2012 alors que le remboursement en capital n&rsquo;\u00e9tait que de 21 M\u20ac, soit une augmentation de la dette de 19 M\u20ac.<\/p>\n<p>Il a demand\u00e9 que l&rsquo;on fasse encore un effort de r\u00e9duction des investissements afin d\u2019\u00e9viter ce recours trop important \u00e0 l\u2019emprunt. Sans le dire, le Pr\u00e9sident lui a donn\u00e9 raison, concluant le d\u00e9bat en \u00e9voquant un emprunt qui se limiterait \u00e0 30 M\u20ac en 2012. Et comme le programme d\u2019investissement ne serait pas compl\u00e8tement r\u00e9alis\u00e9, il est possible que la dette reste stable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il faut marquer l\u2019ann\u00e9e 2011 d\u2019une pierre blanche car pour la premi\u00e8re fois depuis sa cr\u00e9ation, la M\u00e9tro voit sa dette tr\u00e8s l\u00e9g\u00e8rement diminuer. Il vaut mieux parler de stabilisation car la diminution de 0,5 M\u20ac du stock sur 350 M\u20ac est symbolique. C\u2019est une bonne nouvelle, mais acquise gr\u00e2ce aux fortes augmentations de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[11],"tags":[19,32],"class_list":["post-5206","post","type-post","status-publish","format-standard","hentry","category-politique-locale","tag-impots","tag-metro"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/5206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=5206"}],"version-history":[{"count":2,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/5206\/revisions"}],"predecessor-version":[{"id":5208,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/5206\/revisions\/5208"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=5206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=5206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=5206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}