{"id":7183,"date":"2013-06-08T10:19:50","date_gmt":"2013-06-08T08:19:50","guid":{"rendered":"http:\/\/www.ades-grenoble.org\/wordpress\/?p=7183"},"modified":"2013-06-08T10:19:50","modified_gmt":"2013-06-08T08:19:50","slug":"politique-politicienne-la-gauche-tacle-la-droite-sembrouille","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2013\/06\/08\/politique-politicienne-la-gauche-tacle-la-droite-sembrouille\/","title":{"rendered":"Politique politicienne : la gauche tacle, la droite s&#8217;embrouille"},"content":{"rendered":"<h3>Quand J. Safar tacle G. Fioraso<\/h3>\n<p>A propos de l\u2019attractivit\u00e9 du territoire de la M\u00e9tro, J. Safar a d\u00e9clar\u00e9 le 30 mai\u00a0au journal des entreprises : \u00ab\u00a0 Apr\u00e8s cinq ans d\u2019absence, la M\u00e9tro \u00e9tait pr\u00e9sente au Mipim 2013 ; c\u2019\u00e9tait l\u2019occasion de r\u00e9aliser que nous avons perdu le fil\u2026 Il faut que l\u2019on se donne un sacr\u00e9 coup de pied aux fesses !\u00a0\u00bb. Le Mipim est le salon mondial de l\u2019immobilier et des investisseurs. Rappel, durant les 5 ans en question, c\u2019est G. Fioraso qui \u00e9tait aux commandes.<\/p>\n<h3>A droite, tout se complique<\/h3>\n<p>Alors que Chamussy s\u2019\u00e9tait engag\u00e9, comme les autres candidats UMP, \u00e0 participer \u00e0 la liste du vainqueur de la primaire, il revient maintenant sur cet engagement. Il a donc re\u00e7u un carton jaune du pr\u00e9sident de l\u2019UMP38. Il faut dire que participer \u00e0 cette primaire avec l\u2019ex-maire corrompu, ce n\u2019est pas une sin\u00e9cure. Chacun doit y aller de sa surench\u00e8re, par exemple lors du d\u00e9bat sur la s\u00e9curit\u00e9, A. Carignon a propos\u00e9 une vente massive des logements sociaux afin de responsabiliser les propri\u00e9taires, sous entendu ce sont les locataires facteurs d\u2019ins\u00e9curit\u00e9 ! Chamussy est pour armer jour et nuit la police municipale\u2026 Bref cela n\u2019a pas vol\u00e9 tr\u00e8s haut.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand J. Safar tacle G. Fioraso A propos de l\u2019attractivit\u00e9 du territoire de la M\u00e9tro, J. Safar a d\u00e9clar\u00e9 le 30 mai\u00a0au journal des entreprises : \u00ab\u00a0 Apr\u00e8s cinq ans d\u2019absence, la M\u00e9tro \u00e9tait pr\u00e9sente au Mipim 2013 ; c\u2019\u00e9tait l\u2019occasion de r\u00e9aliser que nous avons perdu le fil\u2026 Il faut que l\u2019on se donne [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[11],"tags":[30,115],"class_list":["post-7183","post","type-post","status-publish","format-standard","hentry","category-politique-locale","tag-corrompu","tag-municipales-2014"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/7183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=7183"}],"version-history":[{"count":2,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/7183\/revisions"}],"predecessor-version":[{"id":7185,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/7183\/revisions\/7185"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=7183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=7183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=7183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}