{"id":7830,"date":"2013-12-06T21:48:32","date_gmt":"2013-12-06T19:48:32","guid":{"rendered":"http:\/\/www.ades-grenoble.org\/wordpress\/?p=7830"},"modified":"2013-12-06T21:48:32","modified_gmt":"2013-12-06T19:48:32","slug":"protection-de-lenfance-le-bras-de-fer-se-poursuit","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2013\/12\/06\/protection-de-lenfance-le-bras-de-fer-se-poursuit\/","title":{"rendered":"Protection de l\u2019enfance : le bras de fer se poursuit"},"content":{"rendered":"<div id=\"attachment_6963\" style=\"width: 160px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6963\" class=\"size-thumbnail wp-image-6963\" alt=\"Mobilisation des travailleurs sociaux devant le conseil g\u00e9n\u00e9ral - 12\/4\/13\" src=\"http:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2013\/04\/130412-social-cg38-150x100.jpg\" width=\"150\" height=\"100\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2013\/04\/130412-social-cg38-150x100.jpg 150w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2013\/04\/130412-social-cg38-300x200.jpg 300w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2013\/04\/130412-social-cg38.jpg 640w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><p id=\"caption-attachment-6963\" class=\"wp-caption-text\">Mobilisation des travailleurs sociaux devant le conseil g\u00e9n\u00e9ral &#8211; 12\/4\/13<\/p><\/div>\n<p>On se souvient que le 12 avril dernier l\u2019ex\u00e9cutif du Conseil g\u00e9n\u00e9ral avait minimis\u00e9 la r\u00e9alit\u00e9 d\u2019un document interne de travail qui faisait \u00e9tat de la <a href=\"http:\/\/www.ades-grenoble.org\/wordpress\/2013\/04\/12\/protection-de-lenfance-etape-positive-au-conseil-general-mais-la-vigilance-reste-de-mise\/\">suppression en Is\u00e8re de 300 places d\u2019accueil d\u2019enfants et de jeunes en difficult\u00e9<\/a> et son corollaire la suppression de 180 emplois. Pour donner le change et sous la pression de plusieurs manifestations de travailleurs sociaux, le pr\u00e9sident du Conseil g\u00e9n\u00e9ral avait accept\u00e9 la mise en place de groupes de r\u00e9flexion sans avoir abandonn\u00e9 l\u2019id\u00e9e d\u2019\u00e9laborer un sch\u00e9ma d\u00e9partemental d\u2019action sociale. O\u00f9 en est-on 7 mois apr\u00e8s\u00a0? Les organisations syndicales CGT, SUD Is\u00e8re et CFDT, viennent de le faire savoir dans une lettre ouverte commune adress\u00e9e \u00e0 A. Vallini dont voici quelques extraits.<\/p>\n<p><!--more-->\u00ab\u2026Nous avions fait part de notre volont\u00e9 d\u2019\u00eatre \u00e9troitement associ\u00e9s aux diff\u00e9rents stades de cette d\u00e9marche collective (NDLR \u00e9laboration du sch\u00e9ma d\u2019action sociale), car nous ne manquons ni d\u2019observations ni de propositions\u2026 En effet il para\u00eet inconcevable que\u00a0 notre avis ne soit pas pris en compte\u2026 nous avons particip\u00e9 activement \u00e0 l\u2019ensemble des travaux\u2026 Lors de la r\u00e9union de restitution du 25 septembre 2013, nous avons regrett\u00e9 votre absence alors que votre pr\u00e9sence avait \u00e9t\u00e9 annonc\u00e9e, nous avons \u00e9t\u00e9 surpris d\u2019entendre que \u00ab\u00a0le financement des nouveaux projets sera assur\u00e9 par le red\u00e9ploiement financier effectu\u00e9 gr\u00e2ce aux \u00e9conomies r\u00e9alis\u00e9es sur la partie h\u00e9bergement\u00a0\u00bb\u2026 Aujourd\u2019hui nous reposons la m\u00eame question\u00a0: soit le sch\u00e9ma d\u00e9partemental sert \u00e0 mettre en perspective une r\u00e9elle politique de pr\u00e9vention et de protection de l\u2019enfance avec les moyens mat\u00e9riels et humains n\u00e9cessaires, soit c\u2019est simplement \u00eatre dans les clous r\u00e9glementaires sans r\u00e9els moyens\u2026 Dans le dispositif de protection de l\u2019enfance, la p\u00e9nurie de moyens ne peut que conduire \u00e0 une d\u00e9gradation des situations des enfants, des familles mais aussi des professionnels de la protection de l\u2019enfance. Et ceci vous le savez mieux que quiconque. Aujourd\u2019hui nous sommes inquiets de voir le nombre d\u2019enfants \u00e0 prendre en charge, de voir les structures d\u2019accueil et de suivi d\u00e9bord\u00e9es sans que suivent les effectifs et les moyens mat\u00e9riels n\u00e9cessaires. Par ricochet, les salari\u00e9s qui ne peuvent pas effectuer leur mission sont en souffrance\u2026 Aussi nous sommes d\u00e9concert\u00e9s par la m\u00e9thode appliqu\u00e9e pour l\u2019\u00e9laboration d ce sch\u00e9ma. M\u00e9thode d\u2019autant plus insupportable pour les professionnels qu\u2019elle est propos\u00e9e par vous m\u00eame qui avez la volont\u00e9 de faire de la lutte contre la maltraitance des enfants la Grande Cause Nationale 2014. L\u2019Is\u00e8re qui devrait \u00eatre d\u00e9partement pilote risque de devenir un contre-exemple\u2026 L\u2019intersyndicale reste donc vigilante et mobilisera les professionnels qui dans leur globalit\u00e9 sont inquiets de l\u2019avenir de la protection de l\u2019enfance en Is\u00e8re. Nos revendications restent les m\u00eames \u00e0 savoir\u00a0: pas de suppression de postes, pas de d\u00e9gradation des conditions de travail et des budgets \u00e0 la hauteur des besoins r\u00e9ellement rep\u00e9r\u00e9s et discut\u00e9s\u2026\u00a0\u00bb.<\/p>\n<p>R\u00e9ponse du Pr\u00e9sident du Conseil g\u00e9n\u00e9ral apr\u00e8s les \u00e9lections\u00a0? Parce qu\u2019avant, A. Vallini, qui n\u2019est plus \u00e0 un paradoxe pr\u00e8s se fend dans le dernier num\u00e9ro du magazine du Conseil g\u00e9n\u00e9ral d\u2019un \u00e9ditorial \u00e0 vous tirer des larmes : \u00ab\u00a0ce mot si beau de solidarit\u00e9\u00a0\u00bb. Et, toute honte bue, il \u00e9voque l\u2019action sociale, \u00ab\u00a0comp\u00e9tence majeure du Conseil g\u00e9n\u00e9ral, \u2026la vie des plus pauvres, des plus humbles, des plus malheureux\u2026les familles en difficult\u00e9s\u2026 nous voulons dire merci \u00e0 ces Is\u00e9rois qui donnent du sens au mot si beau de solidarit\u00e9\u00a0\u00bb De l\u2019avis g\u00e9n\u00e9ral, personne et certainement pas les jeunes en difficult\u00e9 et les travailleurs sociaux n\u2019imagineraient dire merci \u00e0 celui qui se moque bien de donner un sens \u00e0 solidarit\u00e9<\/p>\n","protected":false},"excerpt":{"rendered":"<p>On se souvient que le 12 avril dernier l\u2019ex\u00e9cutif du Conseil g\u00e9n\u00e9ral avait minimis\u00e9 la r\u00e9alit\u00e9 d\u2019un document interne de travail qui faisait \u00e9tat de la suppression en Is\u00e8re de 300 places d\u2019accueil d\u2019enfants et de jeunes en difficult\u00e9 et son corollaire la suppression de 180 emplois. Pour donner le change et sous la pression [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[11],"tags":[22,33,107],"class_list":["post-7830","post","type-post","status-publish","format-standard","hentry","category-politique-locale","tag-conseil-general-de-lisere","tag-social","tag-vallini"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/7830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=7830"}],"version-history":[{"count":3,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/7830\/revisions"}],"predecessor-version":[{"id":7833,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/7830\/revisions\/7833"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=7830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=7830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=7830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}