{"id":9257,"date":"2014-11-07T09:47:07","date_gmt":"2014-11-07T07:47:07","guid":{"rendered":"http:\/\/www.ades-grenoble.org\/wordpress\/?p=9257"},"modified":"2014-11-07T15:06:12","modified_gmt":"2014-11-07T13:06:12","slug":"conseils-citoyens-de-la-politique-de-la-ville-ca-urge","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2014\/11\/07\/conseils-citoyens-de-la-politique-de-la-ville-ca-urge\/","title":{"rendered":"Conseils citoyens de la politique de la ville, \u00e7a urge !"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9002\" src=\"http:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2014\/09\/JO1.jpg\" alt=\"Journal officiel\" width=\"400\" height=\"189\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2014\/09\/JO1.jpg 400w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2014\/09\/JO1-150x70.jpg 150w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2014\/09\/JO1-300x141.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Une circulaire minist\u00e9rielle du 15 octobre, fixe aux pr\u00e9fets le cadre de travail des futurs contrats de ville qui doivent \u00eatre sign\u00e9s d&rsquo;ici au 30 juin 2015.<\/strong><\/p>\n<p style=\"text-align: justify;\">Cette circulaire revient notamment sur la co-construction du contrat de ville avec les habitants et la mise en place obligatoire des conseils de quartier qui n&rsquo;est pas un enjeu secondaire (sic).<\/p>\n<p style=\"text-align: justify;\">La circulaire rappelle les exigences de la loi\u00a0: ces conseils doivent \u00eatre autonomes des acteurs institutionnels et ils doivent \u00eatre compos\u00e9s d\u2019habitants (tir\u00e9s au sort) repr\u00e9sentatifs du quartier et des associations et acteurs locaux. Ils doivent \u00eatre partie prenante des instances de pilotage du contrat de ville.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">La mise en \u0153uvre du contrat de ville sera suspendue \u00e0 la mise en place effective du ou des conseils citoyens dans les quartiers de la politique de la ville.<\/p>\n<p style=\"text-align: justify;\">Si les conseils ne sont pas install\u00e9s\u00a0avant la signature du contrat, il appartiendra au pr\u00e9fet de rechercher, en concertation avec les collectivit\u00e9s locales, les associations de quartier et les diff\u00e9rents acteurs locaux, les modalit\u00e9s les plus appropri\u00e9es d&rsquo;association des habitants, notamment les jeunes, \u00e0 l&rsquo;\u00e9laboration des contrats, et de fixer l&rsquo;\u00e9ch\u00e9ance de leur cr\u00e9ation.<\/p>\n<p style=\"text-align: justify;\">Autre point important en ce qui concerne les associations qui agissent dans ces quartiers, la circulaire demande que le contrat de ville d\u00e9cline \u00ab\u00a0les mesures nationales de soutien aux associations de nature \u00e0 simplifier leurs d\u00e9marches et \u00e0 leur donner davantage de visibilit\u00e9, de p\u00e9rennit\u00e9 et d&rsquo;autonomie dans leurs interventions\u00a0\u00bb en encourageant les conventions pluriannuelles d&rsquo;objectifs (CPO) de trois ans pour les \u00ab\u00a0associations les plus structurantes pour le quartier prioritaire\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify;\">Donc il\u00a0; y a urgence pour que soit mis en place ces conseils citoyens dans les quartiers prioritaires et afin d\u2019\u00e9viter des doublons il serait avantageux de les inclure dans les prochains Conseils Citoyens Ind\u00e9pendants qui seront cr\u00e9\u00e9s en 2015 par la ville de Grenoble et dont un acte essentiel sera de d\u00e9cider du budget participatif du secteur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une circulaire minist\u00e9rielle du 15 octobre, fixe aux pr\u00e9fets le cadre de travail des futurs contrats de ville qui doivent \u00eatre sign\u00e9s d&rsquo;ici au 30 juin 2015. Cette circulaire revient notamment sur la co-construction du contrat de ville avec les habitants et la mise en place obligatoire des conseils de quartier qui n&rsquo;est pas un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[35,33],"class_list":["post-9257","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-democratie-locale","tag-social"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/9257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=9257"}],"version-history":[{"count":1,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/9257\/revisions"}],"predecessor-version":[{"id":9258,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/9257\/revisions\/9258"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=9257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=9257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=9257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}