{"id":9395,"date":"2014-12-05T18:17:32","date_gmt":"2014-12-05T16:17:32","guid":{"rendered":"http:\/\/www.ades-grenoble.org\/wordpress\/?p=9395"},"modified":"2014-12-05T18:57:10","modified_gmt":"2014-12-05T16:57:10","slug":"defendons-le-principe-de-limpot","status":"publish","type":"post","link":"https:\/\/www.ades-grenoble.org\/wordpress\/2014\/12\/05\/defendons-le-principe-de-limpot\/","title":{"rendered":"D\u00e9fendons le principe de l\u2019imp\u00f4t"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-9396 size-full\" src=\"http:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2014\/12\/declaration-droits.jpg\" alt=\"declaration droits\" width=\"353\" height=\"450\" srcset=\"https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2014\/12\/declaration-droits.jpg 353w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2014\/12\/declaration-droits-117x150.jpg 117w, https:\/\/www.ades-grenoble.org\/wordpress\/wp-content\/uploads\/2014\/12\/declaration-droits-235x300.jpg 235w\" sizes=\"auto, (max-width: 353px) 100vw, 353px\" \/>La d\u00e9claration des droits de l\u2019homme et du citoyen d\u2019ao\u00fbt 1789, qui fait partie de notre constitution, fonde l\u2019obligation de l\u2019imp\u00f4t dans son article 13\u00a0:<\/p>\n<p style=\"text-align: justify;\"><em>\u00ab\u00a0Pour l&rsquo;entretien de la force publique, et pour les d\u00e9penses d&rsquo;administration, une contribution commune est indispensable : elle doit \u00eatre \u00e9galement r\u00e9partie entre tous les citoyens, en raison de leurs facult\u00e9s.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">L\u2019expression de contribution commune est autrement plus porteuse de sens que le terme d\u00e9cri\u00e9 d\u2019imp\u00f4t.<\/p>\n<p style=\"text-align: justify;\">Il faudrait rappeler cette d\u00e9finition tr\u00e8s simple au gouvernement et au pr\u00e9sident de la R\u00e9publique qui d\u00e9cide de faire cadeau de l\u2019imp\u00f4t aux organisateurs des spectacles sportifs \u00e0 l\u2019occasion des grandes comp\u00e9titions sportives <em>\u00ab\u00a0pour convaincre des jeunes de pratiquer une discipline <\/em>[et pour]<em> qu&rsquo;ils aient le sentiment que \u00e7a se passe tout pr\u00e8s de chez eux\u00a0\u00bb.<\/em><\/p>\n<p style=\"text-align: justify;\"><!--more-->M\u00eame rappel, \u00e0 MM. Cottalorda et Vallini, \u00e0 propos de Center Parcs qui fonde ce projet sur la d\u00e9fiscalisation des propri\u00e9taires des cottages et permet de d\u00e9fricher des centaines d\u2019hectares d\u2019une for\u00eat et de d\u00e9truire le ch\u00e2teau d\u2019eau d\u2019une grande partie de la Dr\u00f4me.<\/p>\n<p style=\"text-align: justify;\">M\u00eame rappel \u00e0 ceux qui rembourse ST Microelectronics \u00e0 Crolles de ses imp\u00f4ts locaux pourtant indispensables pour apporter des services publics aux salari\u00e9s de cette entreprise dans ce territoire.<\/p>\n<p style=\"text-align: justify;\">Profitons-en pour faire remarquer que les imp\u00f4ts locaux, pour les m\u00e9nages et les entreprises ne sont pas du tout conformes \u00e0 la constitution\u00a0: ils ne sont pas r\u00e9partis, en raison des facult\u00e9s des contribuables.\u00a0 A quand une vraie r\u00e9forme de la fiscalit\u00e9 locale, promise et jamais r\u00e9alis\u00e9e\u00a0?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La d\u00e9claration des droits de l\u2019homme et du citoyen d\u2019ao\u00fbt 1789, qui fait partie de notre constitution, fonde l\u2019obligation de l\u2019imp\u00f4t dans son article 13\u00a0: \u00ab\u00a0Pour l&rsquo;entretien de la force publique, et pour les d\u00e9penses d&rsquo;administration, une contribution commune est indispensable : elle doit \u00eatre \u00e9galement r\u00e9partie entre tous les citoyens, en raison de leurs [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[62,11],"tags":[22,35],"class_list":["post-9395","post","type-post","status-publish","format-standard","hentry","category-le-rouge-le-vert-hebdo","category-politique-locale","tag-conseil-general-de-lisere","tag-democratie-locale"],"_links":{"self":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/9395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/comments?post=9395"}],"version-history":[{"count":1,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/9395\/revisions"}],"predecessor-version":[{"id":9397,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/posts\/9395\/revisions\/9397"}],"wp:attachment":[{"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/media?parent=9395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/categories?post=9395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ades-grenoble.org\/wordpress\/wp-json\/wp\/v2\/tags?post=9395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}